{"id":7914,"date":"2016-04-15T08:47:27","date_gmt":"2016-04-15T08:47:27","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=7914"},"modified":"2016-04-14T11:49:09","modified_gmt":"2016-04-14T11:49:09","slug":"destaque-da-tv-aberta-15042016","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/destaque-da-tv-aberta-15042016\/","title":{"rendered":"Destaque da TV Aberta 15\/04\/2016"},"content":{"rendered":"<p>SEXTA-FEIRA, 15\/4<\/p>\n<p>TV Fama<br \/>\nO programa traz not\u00edcias, atualidades, curiosidades do meio art\u00edstico e o que rola nos bastidores. Irreverente e din\u00e2mico, mostra entrevistas, fofocas dos famosos, al\u00e9m de estreias de filmes, pe\u00e7as, eventos, desfiles e lan\u00e7amentos. Uma equipe de rep\u00f3rteres vai \u00e0s ruas para captar flagrantes e perseguir as celebridades em diversos lugares e situa\u00e7\u00f5es. E ainda invade as festas dos Vips e faz a cobertura dos shows mais badalados. \u00c0s 19h na RedeTV.<\/p>\n<p>A Recruta Hollywood<br \/>\nA estrela de cinema Megan Valentine decide se alistar no Ex\u00e9rcito para provar seu talento a um diretor de cinema que n\u00e3o a considera adequada para um filme baseado no servi\u00e7o militar. Uma vez no acampamento, ela se d\u00e1 conta de que cometeu um erro, mas decide persistir com seu prop\u00f3sito para n\u00e3o decepcionar o seu pa\u00eds. \u00c0s 15h06 na Globo.<\/p>\n<p>S\u00e1bado, 16\/4<\/p>\n<p>Agentes da S.H.I.E.L.D.<br \/>\nO agente Phil Coulson organiza um grupo altamente especializado para resolver casos ainda n\u00e3o classificados, em uma organiza\u00e7\u00e3o conhecida como S.H.I.E.L.D. \u00c0 1h14 na Globo.<\/p>\n<p>Dragon Ball Z Kai<br \/>\nAo descobrir que pertence a uma ra\u00e7a de super-humanos que foi enviada \u00e0 terra para domin\u00e1-la, Goku rejeita sua miss\u00e3o e passa a proteger o planeta que o acolheu de todos os malfeitores que surgem no decorrer da saga. \u00c0s 6h na Band.<\/p>\n<p>Mr. Bean<br \/>\nEle vive situa\u00e7\u00f5es que poderiam acontecer em qualquer lugar, em qualquer \u00e9poca. Mas suas hist\u00f3rias acontecem na Inglaterra. Isso torna tudo mais sutil, inesperado, absurdo e engra\u00e7ado. Ele \u00e9 um dos mais atrapalhados personagens que o mundo j\u00e1 conheceu. \u00c0s 22h15 na Band.<\/p>\n<p>DOMINGO, 17\/4<br \/>\nP\u00e2nico na Band<br \/>\nTrupe formada por atores, comediantes, imitadores e apresentadores satiriza a Pol\u00edtica, Esporte, universo da m\u00fasica, celebridades e os mais diversos grupos sociais. Uma sucess\u00e3o de esquetes de humor e reportagens debochadas. \u00c0s 21h20 na Band.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SEXTA-FEIRA, 15\/4 TV Fama O programa traz not\u00edcias, atualidades, curiosidades do meio art\u00edstico e o que rola nos bastidores. Irreverente e din\u00e2mico, mostra entrevistas, fofocas dos famosos, al\u00e9m de estreias de filmes, pe\u00e7as, eventos, desfiles e lan\u00e7amentos. Uma equipe de rep\u00f3rteres vai \u00e0s ruas para captar flagrantes e perseguir as celebridades em diversos lugares e &#8230;<\/p>\n","protected":false},"author":1,"featured_media":7915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[53],"tags":[60],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7914"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=7914"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7914\/revisions"}],"predecessor-version":[{"id":7916,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7914\/revisions\/7916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/7915"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=7914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=7914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=7914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}