{"id":7776,"date":"2016-04-08T08:01:47","date_gmt":"2016-04-08T08:01:47","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=7776"},"modified":"2016-04-07T12:04:42","modified_gmt":"2016-04-07T12:04:42","slug":"destaque-da-tv-aberta-08042016","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/destaque-da-tv-aberta-08042016\/","title":{"rendered":"Destaque da TV Aberta 08\/04\/2016"},"content":{"rendered":"<p>SEXTA-FEIRA, 8\/4<\/p>\n<p>TV Fama<br \/>\nO programa traz not\u00edcias, atualidades, curiosidades do meio art\u00edstico e o que rola nos bastidores. Irreverente e din\u00e2mico, mostra entrevistas, fofocas dos famosos, al\u00e9m de estreias de filmes, pe\u00e7as, eventos, desfiles e lan\u00e7amentos. Uma equipe de rep\u00f3rteres vai \u00e0s ruas para captar flagrantes e perseguir as celebridades em diversos lugares e situa\u00e7\u00f5es. E ainda invade as festas dos Vips e faz a cobertura dos shows mais badalados. \u00c0s 19h na RedeTV.<\/p>\n<p>O Auto da Compadecida<br \/>\nO esperto Jo\u00e3o Grilo e o sonso Chic\u00f3, dois sertanejos pobret\u00f5es, passam a perna em um punhado de moradores de uma cidadezinha do Nordeste. At\u00e9 que Grilo, depois de se defrontar com um temido cangaceiro, presta contas de seus atos a Cristo, ao dem\u00f4nio e a Nossa Senhora. O filme \u00e9 baseado na obra de Ariano Suassuna. \u00c0s 15h05 na Globo.<\/p>\n<p>SUCKER PUNCH: MUNDO SURREAL<br \/>\n\u00c0s v\u00e9speras de ser lobotomizada, a jovem Babydoll encontra em sua imagina\u00e7\u00e3o uma maneira de se proteger da dura realidade do hosp\u00edcio. Em sua mente, ela e algumas amigas enfrentam uma perigosa aventura em busca de uma sa\u00edda real. \u00c0s 23h15 no SBT.<\/p>\n<p>S\u00e1bado, 9\/4<\/p>\n<p>24 Horas &#8211; Viva um Novo Dia<br \/>\nJack Bauer precisa voltar ao combate, em Londres, para impedir um ataque terrorista contra o presidente dos EUA. \u00c0 0h34 na Globo.<br \/>\nDragon Ball Z Kai<br \/>\nAo descobrir que pertence a uma ra\u00e7a de super-humanos que foi enviada \u00e0 terra para domin\u00e1-la, Goku rejeita sua miss\u00e3o e passa a proteger o planeta que o acolheu de todos os malfeitores que surgem no decorrer da saga. \u00c0s 6h na Band.<\/p>\n<p>S\u00e1bado Animal<br \/>\nO programa mostra os mais completos e premiados document\u00e1rios do mundo. \u00c0s 14h50 na Band.<br \/>\nDOMINGO, 10\/4<\/p>\n<p>P\u00e2nico na Band<br \/>\nUma trupe formada por atores, comediantes, imitadores e apresentadores satiriza a Pol\u00edtica, Esporte, universo da m\u00fasica, celebridades e os mais diversos grupos sociais. Uma sucess\u00e3o de esquetes de humor e reportagens debochadas. \u00c0s 21h20 na Band.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SEXTA-FEIRA, 8\/4 TV Fama O programa traz not\u00edcias, atualidades, curiosidades do meio art\u00edstico e o que rola nos bastidores. Irreverente e din\u00e2mico, mostra entrevistas, fofocas dos famosos, al\u00e9m de estreias de filmes, pe\u00e7as, eventos, desfiles e lan\u00e7amentos. Uma equipe de rep\u00f3rteres vai \u00e0s ruas para captar flagrantes e perseguir as celebridades em diversos lugares e &#8230;<\/p>\n","protected":false},"author":1,"featured_media":7777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[53],"tags":[60],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7776"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=7776"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7776\/revisions"}],"predecessor-version":[{"id":7778,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7776\/revisions\/7778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/7777"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=7776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=7776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=7776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}