{"id":7515,"date":"2016-03-25T08:09:46","date_gmt":"2016-03-25T08:09:46","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=7515"},"modified":"2016-03-24T12:12:09","modified_gmt":"2016-03-24T12:12:09","slug":"destaque-da-tv-aberta-25032016","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/destaque-da-tv-aberta-25032016\/","title":{"rendered":"Destaque da TV Aberta 25\/03\/2016"},"content":{"rendered":"<p>SEXTA-FEIRA, 25\/3<\/p>\n<p>TV Fama<br \/>\nO programa traz not\u00edcias, atualidades, curiosidades do meio art\u00edstico e o que rola nos bastidores. Irreverente e din\u00e2mico, mostra entrevistas, fofocas dos famosos, al\u00e9m de estreias de filmes, pe\u00e7as, eventos, desfiles e lan\u00e7amentos. Uma equipe de rep\u00f3rteres vai \u00e0s ruas para captar flagrantes e perseguir as celebridades em diversos lugares e situa\u00e7\u00f5es. E ainda invade as festas dos Vips e faz a cobertura dos shows mais badalados. \u00c0s 19h na RedeTV.<\/p>\n<p>Lara Croft: Tomb Raider<br \/>\nExplorar imp\u00e9rios perdidos, descobrir tesouros e lutar em combates mortais \u00e9 o dia a dia da aventureira Lara Croft. Mas um antigo segredo do pai leva a mo\u00e7a ao seu maior desafio: o tri\u00e2ngulo de luz, uma rel\u00edquia lend\u00e1ria que altera tempo e espa\u00e7o. Lara precisa encontrar o tri\u00e2ngulo antes que caia nas m\u00e3os de uma sociedade secreta que quer dominar o mundo. Aventura baseada em famoso videogame. \u00c0s 15h05 na Globo.<\/p>\n<p>S\u00e1bado, 26\/3<\/p>\n<p>Perception: Truques da Mente<br \/>\nO Dr. Daniel Pierce (Eric MacCormac) \u00e9 um neurocientista que usa suas habilidades para ajudar o FBI. Professor talentoso e paranoico, ele apresenta um conhecimento \u00fanico a respeito do comportamento humano e do funcionamento do c\u00e9rebro. \u00c0s 0h47 na Globo.<\/p>\n<p>S\u00e1bado Animal<br \/>\nO programa mostra os mais completos e premiados document\u00e1rios do mundo. \u00c0s 13h45 na Band.<\/p>\n<p>Mr. Bean<br \/>\nEle vive situa\u00e7\u00f5es que poderiam acontecer em qualquer lugar, em qualquer \u00e9poca. Mas suas hist\u00f3rias acontecem na Inglaterra. Isso torna tudo mais sutil, inesperado, absurdo e engra\u00e7ado. Ele \u00e9 um dos mais atrapalhados personagens que o mundo j\u00e1 conheceu. \u00c0s 22h20 na Band.<\/p>\n<p>DOMINGO, 27\/3<br \/>\nP\u00e2nico na Band<br \/>\nUma trupe formada por atores, comediantes, imitadores e apresentadores satiriza a Pol\u00edtica, Esporte, universo da m\u00fasica, celebridades e os mais diversos grupos sociais. Uma sucess\u00e3o de esquetes de humor e reportagens debochadas. \u00c0s 21h20 na Band.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SEXTA-FEIRA, 25\/3 TV Fama O programa traz not\u00edcias, atualidades, curiosidades do meio art\u00edstico e o que rola nos bastidores. Irreverente e din\u00e2mico, mostra entrevistas, fofocas dos famosos, al\u00e9m de estreias de filmes, pe\u00e7as, eventos, desfiles e lan\u00e7amentos. Uma equipe de rep\u00f3rteres vai \u00e0s ruas para captar flagrantes e perseguir as celebridades em diversos lugares e &#8230;<\/p>\n","protected":false},"author":1,"featured_media":7516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[53],"tags":[60],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7515"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=7515"}],"version-history":[{"count":2,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7515\/revisions"}],"predecessor-version":[{"id":7518,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7515\/revisions\/7518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/7516"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=7515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=7515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=7515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}