{"id":4925,"date":"2015-10-30T08:12:33","date_gmt":"2015-10-30T08:12:33","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=4925"},"modified":"2015-10-29T11:14:48","modified_gmt":"2015-10-29T11:14:48","slug":"destaque-da-tv-aberta-30102015","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/destaque-da-tv-aberta-30102015\/","title":{"rendered":"Destaque da TV Aberta 30\/10\/2015"},"content":{"rendered":"<p>SEXTA-FEIRA, 30\/10<\/p>\n<p>TV Fama<br \/>\nO programa traz not\u00edcias, atualidades, curiosidades do meio art\u00edstico e tudo o que rola nos bastidores. Irreverente e din\u00e2mico, mostra entrevistas, fofocas dos famosos, al\u00e9m de estreias de filmes, pe\u00e7as, eventos, desfiles e lan\u00e7amentos. Uma equipe de rep\u00f3rteres vai \u00e0s ruas para captar flagrantes e perseguir as celebridades em diversos lugares e situa\u00e7\u00f5es. E ainda invade as festas dos Vips e faz a cobertura dos shows mais badalados do momento. \u00c0s 19h na RedeTV.<\/p>\n<p>Os Simpsons<br \/>\nCotidiano da fam\u00edlia de Homer Simpson em uma s\u00e1tira \u00e1cida e politicamente incorreta ao estilo de vida americano. \u00c0s 15h na Band.<\/p>\n<p>Rec\u00e9m-Casados<br \/>\nOs jovens Sarah e Tom se casam e partem para a Europa. A lua de mel \u00e9 complicada e cheia de imprevistos, mas tudo fica ainda pior com a chegada do ex-namorado de Sarah, enviado pelos pais da mo\u00e7a para tentar acabar com o casamento. \u00c0s 15h05 na Globo.<\/p>\n<p>S\u00e1bado, 31\/10<\/p>\n<p>Stalker: Obsess\u00e3o<br \/>\nA tenente Beth Davis lidera uma equipe especializada na investiga\u00e7\u00e3o de crimes ligados \u00e0 persegui\u00e7\u00e3o, como voyeurismo, ass\u00e9dio virtual e fixa\u00e7\u00e3o rom\u00e2ntica. Profissional dedicada, ela esconde um passado traum\u00e1tico, que marcou para sempre sua vida. Beth luta contra o crime ao lado de Jack Larsen, um detetive de personalidade forte e comportamento question\u00e1vel. \u00c0 1h23 na Globo.<\/p>\n<p>S\u00e1bado Animal<br \/>\nO programa mostra os mais completos e premiados document\u00e1rios do mundo. \u00c0s 15h10 na Band.<\/p>\n<p>Top Cine<br \/>\nNa sua faixa nobre semanal a Band reserva uma noite para a sua sess\u00e3o premium de cinema, o TOP CINE. Uma janela dedicada aos filmes de com\u00e9dia, a\u00e7\u00e3o, aventura e suspense. Um festival permanente de sucessos da tela grande. \u00c0s 22h15 na Band.<br \/>\nDOMINGO, 1\/11<\/p>\n<p>P\u00e2nico na Band<br \/>\nUma trupe formada por atores, comediantes, imitadores e apresentadores satiriza a Pol\u00edtica, o Esporte, o universo da m\u00fasica, o mundo das celebridades e os mais diversos grupos sociais. Uma sucess\u00e3o de esquetes de humor e reportagens debochadas. \u00c0s 21h15 na Band.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SEXTA-FEIRA, 30\/10 TV Fama O programa traz not\u00edcias, atualidades, curiosidades do meio art\u00edstico e tudo o que rola nos bastidores. Irreverente e din\u00e2mico, mostra entrevistas, fofocas dos famosos, al\u00e9m de estreias de filmes, pe\u00e7as, eventos, desfiles e lan\u00e7amentos. Uma equipe de rep\u00f3rteres vai \u00e0s ruas para captar flagrantes e perseguir as celebridades em diversos lugares &#8230;<\/p>\n","protected":false},"author":1,"featured_media":4926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[53],"tags":[60],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/4925"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=4925"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/4925\/revisions"}],"predecessor-version":[{"id":4927,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/4925\/revisions\/4927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/4926"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=4925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=4925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=4925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}