{"id":33346,"date":"2021-07-02T10:00:56","date_gmt":"2021-07-02T10:00:56","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=33346"},"modified":"2021-07-01T17:48:25","modified_gmt":"2021-07-01T17:48:25","slug":"evolucao-do-suv-fica-ainda-mais-seguro","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/evolucao-do-suv-fica-ainda-mais-seguro\/","title":{"rendered":"Evolu\u00e7\u00e3o do SUV fica ainda mais seguro"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Modelo tem pre\u00e7o sugerido de r$269.900 na vers\u00e3o touring e r$274.700 no estado de s\u00e3o paulo, por causa do\u00a0ICMS maior<\/strong><\/p>\n<p>O CR-V 2021 chega \u00e0s concession\u00e1rias Honda do Brasil trazendo poucas altera\u00e7\u00f5es externas, mas comum importante refor\u00e7o tecnol\u00f3gico nos sistemas de seguran\u00e7a. O SUV m\u00e9dio feito nos Estados Unidos tem pre\u00e7o sugerido de R$ 269.900 na vers\u00e3o Touring. Ou R$ 274.700 para o Estado de S\u00e3o Paulo, por causa do ICMS maior.<\/p>\n<p>Segundo a Honda, os mais de R$ 60 mil de acr\u00e9scimo em rela\u00e7\u00e3o ao pre\u00e7o da linha 2020 s\u00e3o justificados sobretudo pela perda de valor do real ante o d\u00f3lar. A marca n\u00e3o revelou suas pretens\u00f5es em rela\u00e7\u00e3o \u00e0s vendas, mas informa que devem ser similares \u00e0s de 2020. Ou seja, cerca de 500 unidades por ano.<\/p>\n<p>Trata-se de um grande desafio diante das op\u00e7\u00f5es dispon\u00edveis no mercado, como os renovados Jeep Compass e Peugeot 3008. Bem como os in\u00e9ditos Ford Bronco Sport, Toyota Corolla Cross e Volkswagen Taos. Al\u00e9m do arquirrival Toyota RAV-4, que, diferentemente do Honda, tem tecnologia h\u00edbrida.<\/p>\n<p>Enfim, o grande destaque do novo CR-V Touring \u00e9 o pacote de seguran\u00e7a Honda Sensing. H\u00e1 sistemas ativos como assistente de mudan\u00e7a involunt\u00e1ria de faixa de rolamento e controle de cruzeiro adaptativo (ACC) com ajuste autom\u00e1tico de velocidade. Os dois operam entre 40 km\/h e 145 km\/h.<\/p>\n<p>H\u00e1 tamb\u00e9m monitoramento de aten\u00e7\u00e3o do motorista e controle vetorial de torque ligado aos controles de tra\u00e7\u00e3o e estabilidade Seis air bags (frontais, laterais e do tipo cortina), sistema Isofix para fixar assentos infantis e freio de estacionamento el\u00e9trico s\u00e3o itens de s\u00e9rie.<\/p>\n<p>Os sensores e radares de dist\u00e2ncia que atuam com o controle de cruzeiro adaptativo e a frenagem autom\u00e1tica s\u00e3o precisos. Al\u00e9m de manter a dist\u00e2ncia do ve\u00edculo \u00e0 frente, permitem acompanhar o ritmo do tr\u00e2nsito e s\u00e3o bem f\u00e1ceis de acionar.<\/p>\n<p>O assistente de manuten\u00e7\u00e3o de faixa \u00e9 &#8220;exigente&#8221;. Durante a avalia\u00e7\u00e3o, o sistema s\u00f3 funcionou em locais onde havia faixas bem pintadas e definidas na via. Nesse caso, o SUV seguiu bem centralizado nas ruas.<\/p>\n<p>No visual, as altera\u00e7\u00f5es s\u00e3o impercept\u00edveis. A dianteira continua &#8220;bicuda&#8221;, mas perdeu pe\u00e7as cromadas, tipo de acabamento que passa a ser utilizado nas laterais e tampa do porta-malas. Isso ressaltou o desenho das rodas de liga leve de 18 polegadas, que s\u00e3o escurecidas.<\/p>\n<p>Uma boa novidade \u00e9 o sistema de abertura do porta-malas sem uso da chave. Basta se aproximar, com a chave no bolso, e passar o p\u00e9 sob o para-choque.<\/p>\n<p>Na cabine, a parte superior \u00e9 revestida com materiais &#8220;classudos&#8221; e suaves ao toque. Do painel intermedi\u00e1rio para baixo, por\u00e9m, \u00e9 uma lamban\u00e7a. H\u00e1 sete tipos diferentes de texturas, incluindo apliques de pl\u00e1stico que imitam madeira.<\/p>\n<p>Outra novidade \u00e9 o bot\u00e3o f\u00edsico no sistema de entretenimento que, segundo a Honda, atende os pedidos dos clientes. Ele \u00e9 bem-vindo, uma vez que a tela de 7&#8243; sens\u00edvel ao toque tem respostas lentas e \u00e9 imprecisa.<\/p>\n<p>Ali\u00e1s, o sistema \u00e9 complicado de usar, com agrupamento confuso e opera\u00e7\u00e3o pouco intuitiva. J\u00e1 o painel de instrumentos \u00e9 bonito, colorido e mostra dados como a rota\u00e7\u00e3o do motor.<\/p>\n<p>Por\u00e9m, quem quiser zerar o hod\u00f4metro parcial, buscar uma segunda indica\u00e7\u00e3o (trip B) ou o consumo m\u00e9dio, ter\u00e1 dificuldade. O head up display, que projeta dados na linha de vis\u00e3o do motorista (n\u00e3o \u00e9 preciso tirar os olhos da via), ajuda muito. Colorido, traz dados resumidos inclusive do navegador GPS.<\/p>\n<p>O novo carregador por indu\u00e7\u00e3o (sem uso de cabos) funciona bem, mas apenas para telefones com tela de at\u00e9 6&#8243;. Ao menos h\u00e1 o alento das portas USB, dos tipos 1 e 1,5 A. H\u00e1 conex\u00e3o por meio das interfaces Android Auto e Apple Carplay.<\/p>\n<p>O teto solar com duas l\u00e2minas \u00e9 bonito e muito funcional. Al\u00e9m disso, serve para distrair as crian\u00e7as em viagens longas.<\/p>\n<p><strong>Desempenho<\/strong><br \/>\nO Honda CR-V Touring 2021 mant\u00e9m o motor 1.5 turbo com inje\u00e7\u00e3o direta da linha 2020, bem como o c\u00e2mbio CVT e a tra\u00e7\u00e3o 4&#215;4. O quatro-cilindros a gasolina gera 190 cv de pot\u00eancia e 24,5 mkgf de torque.<\/p>\n<p>Apesar dos bons n\u00fameros, o trem de for\u00e7a n\u00e3o empolga. Sobretudo em arrancadas, como nas sa\u00eddas de sem\u00e1foros.<\/p>\n<p>Por\u00e9m, depois que deslancha, o CR-V Touring 2021 parece ficar mais esperto. E vai bem ao retomar velocidade, como ocorre em ultrapassagens. Ou seja, o comportamento \u00e9 de um modelo focado em fam\u00edlias.<\/p>\n<p>O amplo espa\u00e7o interno confirma isso. S\u00e3o 2,66 metros de dist\u00e2ncia entre os eixos e o porta-malas tem acesso facilitado. Ali\u00e1s, s\u00e3o 522 litros de capacidade com todos os lugares ocupados. O Honda recebe bem at\u00e9 cinco adultos e suas bagagens.<\/p>\n<p>Segundo a marca, com um litro de gasolina o CR-V Touring 2021 roda at\u00e9 11 km na cidade e 12,3 km na estrada. Gra\u00e7as a melhorias no start&amp;stopo, que desliga e religa o motor sozinho.<\/p>\n<p><strong>Pr\u00f3s\u00a0e Contras Pr\u00f3s- SEGURAN\u00c7A<\/strong><br \/>\nCabine \u00e9 espa\u00e7osa e novo pacote Honda Sensing elevou bastante o n\u00edvel da seguran\u00e7a ativa.<\/p>\n<p><strong>Contras\u00a0&#8211; Acabamento<\/strong><br \/>\nEntre os v\u00e1rios tipos de revestimento, h\u00e1 at\u00e9 pl\u00e1stico imitando madeira; central multim\u00eddia \u00e9 confusa.<\/p>\n<p><strong>Ficha T\u00e9nica\u00a0HONDA CR-V TOURING 2021<\/strong><br \/>\nPre\u00e7o sugerido: R$ 269.900<br \/>\nMotor: 1.5, 4 cil., 16V, turbo, gas.<br \/>\nPot\u00eancia (cv): 190 a 5.600 rpm<br \/>\nTorque (mkgf): 24,5 a 2.000 rpm<br \/>\nC\u00e2mbio: Autom\u00e1tico, CVT<br \/>\nComprimento: 4,63 metros<br \/>\nPeso: 1.629 kg<br \/>\nFonte: Honda<\/p>\n<p><span style=\"font-size: 12px;\">Por:\u00a0Eug\u00eanio Brito \/ Estad\u00e3o<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Modelo tem pre\u00e7o sugerido de r$269.900 na vers\u00e3o touring e r$274.700 no estado de s\u00e3o paulo, por causa do\u00a0ICMS maior O CR-V 2021 chega \u00e0s concession\u00e1rias Honda do Brasil trazendo poucas altera\u00e7\u00f5es externas, mas comum importante refor\u00e7o tecnol\u00f3gico nos sistemas de seguran\u00e7a. O SUV m\u00e9dio feito nos Estados Unidos tem pre\u00e7o sugerido de R$ 269.900 &#8230;<\/p>\n","protected":false},"author":34,"featured_media":33347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9,299],"tags":[6009,489,6008,1079],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/33346"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=33346"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/33346\/revisions"}],"predecessor-version":[{"id":33348,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/33346\/revisions\/33348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/33347"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=33346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=33346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=33346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}