{"id":32022,"date":"2021-05-14T08:00:52","date_gmt":"2021-05-14T08:00:52","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=32022"},"modified":"2021-05-13T20:33:07","modified_gmt":"2021-05-13T20:33:07","slug":"dessa-vez-ajudar-e-nossa-meta","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/dessa-vez-ajudar-e-nossa-meta\/","title":{"rendered":"Dessa vez \u2018Ajudar \u00e9 nossa Meta\u2019"},"content":{"rendered":"<p><strong>Projeto desenvolve habilidades como solidariedade, empatia e cidadania entre os estudantes<\/strong><\/p>\n<p>Durante os meses de mar\u00e7o e abril, os alunos dos s\u00e9timos anos do Col\u00e9gio Meta, Unidades Jardim Regina e Itaici, desenvolveram um Projeto Colaborativo durante as aulas de Educa\u00e7\u00e3o Socioemocional, ministradas pelo professor Renan em todas as turmas. Durante as aulas, elaborou-se um formato de trabalho com vistas ao desenvolvimento das habilidades socioemocionais, por meio de temas relacionados ao cotidiano dos estudantes. A ideia, portanto, foi a de promover a aplica\u00e7\u00e3o pr\u00e1tica das habilidades abordadas ao longo da primeira unidade letiva.<\/p>\n<p>Quando o tema do Projeto foi apresentado para as turmas, consolidou-se a certeza de que esse \u00e9 o caminho a ser percorrido para formar os cidad\u00e3os do futuro, pois os pr\u00e9-adolescentes se envolveram totalmente e o desejo de ajudar o pr\u00f3ximo fez desse projeto um marco na hist\u00f3ria do Col\u00e9gio.<\/p>\n<p>Durante as aulas, refletiu-se a respeito da tem\u00e1tica \u201ca import\u00e2ncia de doar\u201d, proposta em suas diversas perspectivas e, para finalizar, os alunos tiraram a ideia do papel e expandiram o projeto que teve como tema: \u2018Ajudar \u00e9 nossa Meta\u2019!<\/p>\n<p>As arrecada\u00e7\u00f5es de alimentos n\u00e3o perec\u00edveis tiveram in\u00edcio durante o Drive-Trhu de P\u00e1scoa, promovido pelo Col\u00e9gio no in\u00edcio do m\u00eas de abril, e continuaram durante todo o m\u00eas. As doa\u00e7\u00f5es j\u00e1 tinham destino certo, a Associa\u00e7\u00e3o Beneficente Irm\u00e3 Dulce (Abid), que tem como meta oferecer solu\u00e7\u00f5es de prote\u00e7\u00e3o integral, com presteza e excel\u00eancia, apoiadas na compet\u00eancia e no constante aprimoramento dos recursos humanos, visando garantir os direitos da crian\u00e7a e do adolescente na conviv\u00eancia familiar e comunit\u00e1ria. Os pontos de arrecada\u00e7\u00e3o foram instalados nas duas Unidades Escolares e, no final das arrecada\u00e7\u00f5es, apurou-se o resultado de quase uma tonelada de alimentos, entregues \u00e0 Abid na quinta-feira (6).<\/p>\n<p>Esse projeto nos ensina sobre solidariedade, empatia e cidadania. O Col\u00e9gio orgulha-se dos resultados obtidos na arrecada\u00e7\u00e3o e na forma\u00e7\u00e3o desses estudantes t\u00e3o especiais!<\/p>\n<p>O sucesso do projeto se deve ao engajamento de todos, professor, equipe escolar, alunos e seus familiares, parceiros insepar\u00e1veis do Col\u00e9gio e que, mais uma vez abra\u00e7aram uma nobre ideia com muita motiva\u00e7\u00e3o, apoiando a causa sem medir esfor\u00e7os e cultivando a solidariedade e a empatia, t\u00e3o necess\u00e1rias \u00e0 nossa sociedade.<\/p>\n<p>O Col\u00e9gio Meta n\u00e3o para porque considera que seus estudantes s\u00e3o o centro, a raz\u00e3o de ser das suas a\u00e7\u00f5es. Crian\u00e7as e jovens s\u00e3o vida e a vida \u00e9 din\u00e2mica. Aguarde not\u00edcias sobre outros projetos colaborativos!<\/p>\n<p>Para conhecer mais sobre as atividades desenvolvidas pelos profissionais do Col\u00e9gio, acesse o portal www.colegiometa.com ou fa\u00e7a-nos uma visita. A Unidade I est\u00e1 situada na Rua Herm\u00ednio Steffen, 96, Jardim Regina, e a Unidade II, na Avenida Cel. Ant\u00f4nio Estanislau do Amaral, 1.541, Itaici.<\/p>\n<p><a href=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/05\/07-Col\u00e9gio-Meta-1.jpeg\"><img class=\"alignnone  wp-image-32025\" src=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/05\/07-Col\u00e9gio-Meta-1.jpeg\" alt=\"07 - Col\u00e9gio Meta (1)\" width=\"410\" height=\"546\" srcset=\"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/05\/07-Col\u00e9gio-Meta-1.jpeg 768w, https:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/05\/07-Col\u00e9gio-Meta-1-225x300.jpeg 225w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/><\/a><strong>SOLIDARIEDADE<\/strong>\u00a0Durante as aulas, refletiu-se a respeito da tem\u00e1tica \u201ca import\u00e2ncia de doar\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Projeto desenvolve habilidades como solidariedade, empatia e cidadania entre os estudantes Durante os meses de mar\u00e7o e abril, os alunos dos s\u00e9timos anos do Col\u00e9gio Meta, Unidades Jardim Regina e Itaici, desenvolveram um Projeto Colaborativo durante as aulas de Educa\u00e7\u00e3o Socioemocional, ministradas pelo professor Renan em todas as turmas. Durante as aulas, elaborou-se um formato &#8230;<\/p>\n","protected":false},"author":34,"featured_media":32023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,254,16,248,11],"tags":[],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/32022"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=32022"}],"version-history":[{"count":5,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/32022\/revisions"}],"predecessor-version":[{"id":32030,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/32022\/revisions\/32030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/32023"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=32022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=32022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=32022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}