{"id":18710,"date":"2018-02-16T06:00:11","date_gmt":"2018-02-16T06:00:11","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=18710"},"modified":"2018-02-15T11:51:23","modified_gmt":"2018-02-15T11:51:23","slug":"destaques-da-tv-fechada-1602","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/destaques-da-tv-fechada-1602\/","title":{"rendered":"Destaques da TV Fechada 16\/02"},"content":{"rendered":"<p><strong>SEXTA-FEIRA, 16\/2<\/strong><\/p>\n<p><em>Muito bem acompanhada<\/em><br \/>\nKat Ellis volta a Londres para o casamento de sua irm\u00e3. Com medo de encarar o ex-noivo, que a abandonou no altar dois anos antes, ela contrata um acompanhante para fingir ser seu namorado. O que ela n\u00e3o esperava era que ele conquistasse toda a sua fam\u00edlia, demonstrando ser um genro perfeito. \u00c0s 12h40 no Megapix.<\/p>\n<p><em>REDEN\u00c7\u00c3O<\/em><br \/>\nJoey Jones (Jason Statham) \u00e9 um veterano do Ex\u00e9rcito norte-americano que lutou na guerra do Afeganist\u00e3o. Ap\u00f3s ter sua namorada, que estava gr\u00e1vida, assassinada, ele usa seus contatos com a m\u00e1fia chinesa para encontrar a pessoa respons\u00e1vel pelo crime. \u00c0s 19h14 no Space.<\/p>\n<p><em>KARATE KID<\/em><br \/>\nDre Parker, um garoto de 12 anos muda para a China devido ao trabalho da m\u00e3e. Logo ao chegar em Pequim, ele se apaixona por sua colega de classe Mei Tin. A aproxima\u00e7\u00e3o deles provoca a irrita\u00e7\u00e3o de Cheng, um garoto prod\u00edgio no kung fu e o brig\u00e3o da sala. Sem amigos na cidade, Dre recorre ao zelador de seu pr\u00e9dio que \u00e9 mestre em kung fu. Han ensina Dre que kung fu \u00e9 muito mais que socos e habilidades, mas sim maturidade e calma. \u00c0s 21h40 no Warner Channel.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>S\u00c1BADO, 17\/2<\/strong><\/p>\n<p><em>PIRATAS PIRADOS!<\/em><br \/>\nO pirata Capit\u00e3o \u00e9 um aventureiro, embora nem sempre bem-sucedido, terror dos Sete Mares que est\u00e1 com seu barco est\u00e1 em frangalhos. Seu sonho: derrotar Black Bellamy e Cutlass Liz e levar o trof\u00e9u de Pirata do Ano. Para conseguir, Capit\u00e3o vai com sua tripula\u00e7\u00e3o, formada por um albino, uma mulher disfar\u00e7ada de homem e um papagaio, para a ex\u00f3tica Ilha de Sangue at\u00e9 as ruas da Londres vitoriana para batalhar contra a Rainha Vit\u00f3ria na companhia do famoso pesquisador Charles Darwin. \u00c0s 11h04 no Warner Channel.<\/p>\n<p><em>STREET FIGHTER &#8211; A \u00daLTIMA BATALHA<\/em><br \/>\nAdapta\u00e7\u00e3o de um cl\u00e1ssico do videogame. General Bison, o enlouquecido Senhor da Guerra, prende trabalhadores ocidentais, pedindo alto resgate. O coronel Guile monta uma opera\u00e7\u00e3o de resgate em tempo recorde, utilizando lutadores de rua como soldados no confronto com os renegados. \u00c0s 13h35 no Space.<\/p>\n<p><em>Os mercen\u00e1rios<\/em><br \/>\nGrupo de mercen\u00e1rios chefiados pelo temido Barney Ross segue para a Ilha de Vilena, na Am\u00e9rica do Sul, com a miss\u00e3o de derrubar o governo do ditador Garza. Mas, para que a ordem seja cumprida, eles dever\u00e3o desarticular uma perigosa rede criminal e impedir a interven\u00e7\u00e3o de outros pa\u00edses na situa\u00e7\u00e3o. \u00c0s 17h40 no Megapix.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>DOMINGO, 18\/2<\/strong><\/p>\n<p><em>SOLDADO UNIVERSAL<\/em><br \/>\nDois soldados lutam durante um massacre. Por\u00e9m, 23 anos mais tarde s\u00e3o trazidos de volta \u00e0 vida pelo Departamento de Defesa, com a miss\u00e3o de fazerem parte de uma unidade de elite antiterrorista. \u00c0s 9h10 no Space.<\/p>\n<p><em>Noiva em fuga<\/em><br \/>\nAs fracassadas tentativas de casamento de Maggie Carpenter foram parar na coluna do jornalista Ike Graham. Al\u00e9m da frustra\u00e7\u00e3o de ter deixado mais um noivo no altar, Maggie fica furiosa em ter o jornalista atr\u00e1s dela. Mas ela n\u00e3o esperava se apaixonar por ele. \u00c0s 13h35 no Megapix.<\/p>\n<p><em>EU SOU A LENDA<\/em><br \/>\nO \u00faltimo sobrevivente humano de uma epidemia provocada por um terr\u00edvel v\u00edrus de laborat\u00f3rio que deveria curar o c\u00e2ncer tr\u00eas anos antes, o cientista militar Robert Neville (Will Smith) envia religiosamente mensagens de r\u00e1dio todos os dias na esperan\u00e7a de encontrar outra criatura da sua esp\u00e9cie. Mas ele n\u00e3o est\u00e1 totalmente sozinho. Al\u00e9m da companhia de seu c\u00e3o, est\u00e1 cercado de v\u00edtimas mutantes da praga, que observam cada passo seu. Talvez sua \u00fanica sa\u00edda seja tentar reverter os efeitos do v\u00edrus utilizando seu pr\u00f3prio sangue imune. Mas ele est\u00e1 em desvantagem&#8230; e seu tempo est\u00e1 se esgotando. \u00c0s 20h12 no Warner Channel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SEXTA-FEIRA, 16\/2 Muito bem acompanhada Kat Ellis volta a Londres para o casamento de sua irm\u00e3. Com medo de encarar o ex-noivo, que a abandonou no altar dois anos antes, ela contrata um acompanhante para fingir ser seu namorado. O que ela n\u00e3o esperava era que ele conquistasse toda a sua fam\u00edlia, demonstrando ser um &#8230;<\/p>\n","protected":false},"author":30,"featured_media":18713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[51,6],"tags":[2882],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/18710"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=18710"}],"version-history":[{"count":2,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/18710\/revisions"}],"predecessor-version":[{"id":18714,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/18710\/revisions\/18714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/18713"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=18710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=18710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=18710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}