{"id":17567,"date":"2017-12-08T08:22:51","date_gmt":"2017-12-08T08:22:51","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=17567"},"modified":"2017-12-07T19:24:16","modified_gmt":"2017-12-07T19:24:16","slug":"jovem-entre-18-e-24-anos-e-o-terror-das-seguradoras","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/jovem-entre-18-e-24-anos-e-o-terror-das-seguradoras\/","title":{"rendered":"Jovem entre 18 e 24 anos \u00e9 o \u2018terror\u2019 das seguradoras"},"content":{"rendered":"<p><span style=\"font-size: 10px;\"><em>Por\u00a0Rafaela Borges\/AE\u00a0<\/em><\/span><\/p>\n<p>O pre\u00e7o do Seguro de Ve\u00edculos para mulheres n\u00e3o \u00e9 mais inferior ao dos homens. Ou n\u00e3o \u00e9 t\u00e3o mais barato quanto antes. \u201cSe a ap\u00f3lice de um homem custa R$ 1.400, a da mulher com perfil semelhante sair\u00e1 por cerca de R$ 1.300\u201d, diz Rodolfo Lopes, s\u00f3cio de uma corretora.<br \/>\nDe acordo com o corretor, isso pode estar relacionado com o aumento do \u00edndice de sinistralidade entre elas. As seguradoras n\u00e3o falam abertamente sobre grupos de clientes com maior ou menor risco.<br \/>\n\u201cO c\u00e1lculo do valor do Seguro \u00e9 feito com base em v\u00e1rios fatores, como a idade do segurado, seu local de resid\u00eancia e onde ele costuma ir, hist\u00f3rico de dire\u00e7\u00e3o, h\u00e1bitos de utiliza\u00e7\u00e3o do autom\u00f3vel, entre outros\u201d, diz o diretor de outra seguradora, Jaime Soares.<br \/>\nOs corretores de Seguros dizem que esses grupos existem sim. O terror das seguradoras s\u00e3o os jovens com idade entre 18 e 24 anos.<br \/>\nEles s\u00e3o capazes de elevar n\u00e3o apenas o Seguro do pr\u00f3prio carro, mas tamb\u00e9m do ve\u00edculo de seus pais.<br \/>\n\u201cSe o segurado tiver um filho nessa faixa et\u00e1ria, o pre\u00e7o aumenta. Se o filho dirigir o carro do segurado, aumenta mais\u201d, diz Lopes. Isso porque, segundo as estat\u00edsticas, os jovens s\u00e3o o grupo que mais se envolve em acidentes de tr\u00e2nsito.<br \/>\nOutro perfil cujos integrantes pagam mais \u00e9 o de pessoas com n\u00famero de CPF listado em \u00d3rg\u00e3os de Prote\u00e7\u00e3o ao Cr\u00e9dito. Na composi\u00e7\u00e3o do pre\u00e7o do Seguro, considera-se que os endividados s\u00e3o mais estressados, ficando sujeitos a ocorr\u00eancias no tr\u00e2nsito.<br \/>\nO grupo ideal (para a seguradora) \u00e9 formado por pessoas casadas, com mais de 35 anos (independentemente do g\u00eanero). As seguradoras pressup\u00f5em que os solteiros saem mais e t\u00eam rotina menos previs\u00edvel.<br \/>\nTer ou n\u00e3o ter filhos \u00e9 irrelevante, a n\u00e3o ser que sejam do grupo entre 18 e 24 anos e morem na mesma casa dos pais.<br \/>\nOs Seguros para idosos n\u00e3o s\u00e3o mais caros. H\u00e1 casos em que ficam at\u00e9 mais em conta, pois esses motoristas s\u00e3o considerados mais experientes e atenciosos.<br \/>\n\u201cS\u00f3 haver\u00e1 cobran\u00e7a extra se o idoso tiver se envolvido em muitos sinistros\u201d, explica Lopes. Como a composi\u00e7\u00e3o do pre\u00e7o da ap\u00f3lice varia de uma seguradora para outra, n\u00e3o \u00e9 poss\u00edvel mensurar o percentual exato que um grupo paga a mais que outro.<\/p>\n<p><strong>Descontos<\/strong><br \/>\nN\u00e3o \u00e9 tudo que faz aumentar os pre\u00e7os, as seguradoras oferecem facilidades que ajudam a reduzir o valor da ap\u00f3lice. H\u00e1 empresas que oferecem descontos para quem tem o dispositivo \u2018Sem Parar\u2019 no carro ou Cart\u00e3o de Cr\u00e9dito da companhia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por\u00a0Rafaela Borges\/AE\u00a0 O pre\u00e7o do Seguro de Ve\u00edculos para mulheres n\u00e3o \u00e9 mais inferior ao dos homens. Ou n\u00e3o \u00e9 t\u00e3o mais barato quanto antes. \u201cSe a ap\u00f3lice de um homem custa R$ 1.400, a da mulher com perfil semelhante sair\u00e1 por cerca de R$ 1.300\u201d, diz Rodolfo Lopes, s\u00f3cio de uma corretora. De acordo &#8230;<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9,265],"tags":[2935],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/17567"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=17567"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/17567\/revisions"}],"predecessor-version":[{"id":17568,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/17567\/revisions\/17568"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=17567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=17567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=17567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}