{"id":16558,"date":"2017-10-13T06:29:01","date_gmt":"2017-10-13T06:29:01","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=16558"},"modified":"2017-10-12T11:57:22","modified_gmt":"2017-10-12T11:57:22","slug":"porsche-911-e-jaguar-f-type-duelam","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/porsche-911-e-jaguar-f-type-duelam\/","title":{"rendered":"Porsche 911 e Jaguar F-Type duelam"},"content":{"rendered":"<p><strong>Embate entre a discri\u00e7\u00e3o e a ostenta\u00e7\u00e3o, empresas utilizam receitas bem diferentes na concep\u00e7\u00e3o de seus esportivos<\/strong><\/p>\n<p>Um tem motor na frente, enquanto no outro ele est\u00e1 atr\u00e1s. Um tem porta-malas na traseira e no outro, o pequeno compartimento \u00e9 na dianteira. O primeiro \u00e9 ingl\u00eas e o segundo, alem\u00e3o. Jaguar e Porsche utilizam receitas bem diferentes na concep\u00e7\u00e3o de seus esportivos.<br \/>\nCada uma dessas marcas representa uma escola. A Jaguar n\u00e3o economiza na cilindrada e a filosofia da Porsche, de fazer \u2018mais com menos\u2019, inclui motores menores. Reunimos a vers\u00e3o SVR do F-Type SVR e a GTS do 911 n\u00e3o para um comparativo convencional, mas para mostrar a diferen\u00e7a entre essas duas escolas &#8211; at\u00e9 porque a dist\u00e2ncia entre as tabelas desses carros \u00e9 grande. Enquanto o brit\u00e2nico tem pre\u00e7o sugerido de R$ 883 mil, o do alem\u00e3o \u00e9 de R$ 694 mil.<br \/>\nPara mover seu esportivo, a Jaguar optou por um enorme 5.0 V8 supercharger (compressor mec\u00e2nico). O Porsche traz um 3.0 boxer biturbo, de seis cilindros. Em termos de pot\u00eancia, a diferen\u00e7a \u00e9 de 125 cv a favor do brit\u00e2nico. S\u00e3o 575 cv, ante 450 cv do alem\u00e3o.<br \/>\nNo entanto, basta colocar os dois esportivos para acelerar e essa vantagem do V8 come\u00e7a a se diluir. Ambos s\u00e3o ferozes e podem ir de 0 a 100 km\/h nos mesmos 3,7 segundos, de acordo com dados das f\u00e1bricas.<br \/>\nAqui aparece o fator \u2018mais com menos\u2019. Um dos trunfos do 911 \u00e9 ser 235 kg mais leve: seu peso \u00e9 de 1.470 kg, ante os 1.705 kg do F-Type.<br \/>\nNa pr\u00e1tica, o Porsche leva seu motorista ao \u00eaxtase com certa austeridade. O seis-cilindros boxer (deitado) \u00e9 eficiente e silencioso, mesmo com o modo de condu\u00e7\u00e3o esportivo ativado.<br \/>\nJ\u00e1 o berro do V8 do Jaguar aumenta \u00e0 medida que se pressiona o acelerador, e n\u00e3o economiza \u2018estouros\u2019 nas trocas de marcha, especialmente nas redu\u00e7\u00f5es. Acelerar \u00e9 como um evento que deve ser celebrado e compartilhado com todos na rua.<\/p>\n<blockquote><p>Este comparativo serve para para mostrar a diferen\u00e7a entre essas duas escolas<\/p><\/blockquote>\n<p>E com fartura de gasolina: de acordo com dados do Inmetro, o F-Type faz m\u00e9dia de 5,7 km\/l na cidade e 8,6 km\/l na estrada. Com motor menor, o 911 \u00e9 comedido tamb\u00e9m nesse item: faz, em m\u00e9dia, 8,2 km\/l em uso urbano e 11 km\/l em rodovias.<\/p>\n<div id=\"attachment_16539\" style=\"width: 802px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2017\/10\/07-abre-Porsche.jpg\"><img aria-describedby=\"caption-attachment-16539\" class=\"wp-image-16539 \" src=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2017\/10\/07-abre-Porsche.jpg\" alt=\"GTS - O Porsche traz um motor 3.0 boxer biturbo; ambos podem ir de 0 a 100 km\/h em 3,7s\" width=\"792\" height=\"445\" srcset=\"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2017\/10\/07-abre-Porsche.jpg 900w, https:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2017\/10\/07-abre-Porsche-300x169.jpg 300w\" sizes=\"(max-width: 792px) 100vw, 792px\" \/><\/a><p id=\"caption-attachment-16539\" class=\"wp-caption-text\">GTS &#8211; O Porsche traz um motor 3.0 boxer biturbo; ambos podem ir de 0 a 100 km\/h em 3,7s<\/p><\/div>\n<p><em><strong>LUXO<\/strong><\/em><br \/>\nUma grande diferen\u00e7a entre as duas marcas pode ser vista na cabine de seus carros. O Jaguar esbanja luxo e seu acabamento mescla fibra de carbono e revestimento de camur\u00e7a no painel, console e volante. As sa\u00eddas de ar s\u00f3 emergem do painel quando o sistema de climatiza\u00e7\u00e3o \u00e9 acionado.<br \/>\nPerto dele, o 911 at\u00e9 parece um carro simples. Na unidade avaliada do Porsche o volante n\u00e3o tinha nem comandos de som, algo dif\u00edcil de aceitar em um carro de quase R$ 700 mil.<br \/>\nO GTS \u00e9 a s\u00edntese do esportivo. Exceto pelas aletas para troca de marchas, o \u00fanico controle no volante era o seletor que indica o n\u00edvel de esportividade (do normal ao agressivo).<br \/>\nOs dois modelos t\u00eam aerof\u00f3lios m\u00f3veis, teclas para refor\u00e7ar o som do motor e bancos envolventes com ajustes el\u00e9tricos inclusive dos apoios laterais. No Jaguar os comandos, instalados na porta, d\u00e3o um aspecto mais elegante.<br \/>\nO Jaguar tem a configura\u00e7\u00e3o cl\u00e1ssica dos esportivos de dois lugares, com porta-malas (310 litros) acess\u00edvel pela traseira. No 911, al\u00e9m dos assentos da frente h\u00e1 duas acomoda\u00e7\u00f5es min\u00fasculas atr\u00e1s. Mas na pr\u00e1tica o espa\u00e7o \u00e9 tratado pela pr\u00f3pria Porsche como um bagageiro, para 260 litros.<br \/>\nO alem\u00e3o tem tamb\u00e9m um porta-malas na dianteira, com 125 litros de capacidade.<\/p>\n<p><em><strong>OPINI\u00c3O<\/strong><\/em><br \/>\nPara quem gosta de esportivos, as iniciais SVR e GTS dizem muito. No caso do F-Type, a sigla indica que o modelo recebeu um tratamento para real\u00e7ar ainda mais suas caracter\u00edsticas esportivas, como escapamento de tit\u00e2nio, suspens\u00e3o recalibrada, freios com discos de carbono cer\u00e2mica etc. Em rela\u00e7\u00e3o ao F-Type R, essa vers\u00e3o tem 25 cv a mais e 50 kg a menos. Da mesma forma, sempre se pode esperar mais de um Porsche que traga a assinatura GTS. Em rela\u00e7\u00e3o ao 911 Carrera S, s\u00e3o 30 cv a mais. O pacote Sport Chrono, que refor\u00e7a a esportividade, \u00e9 item de s\u00e9rie. Al\u00e9m disso, sua suspens\u00e3o \u00e9 10 mm mais baixa e os freios s\u00e3o similares aos utilizados no 911 Turbo.<\/p>\n<p>&nbsp;<\/p>\n<p>Texto:\u00a0Hairton Ponciano\/AE &#8211; Fotos: Divulga\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Embate entre a discri\u00e7\u00e3o e a ostenta\u00e7\u00e3o, empresas utilizam receitas bem diferentes na concep\u00e7\u00e3o de seus esportivos Um tem motor na frente, enquanto no outro ele est\u00e1 atr\u00e1s. Um tem porta-malas na traseira e no outro, o pequeno compartimento \u00e9 na dianteira. O primeiro \u00e9 ingl\u00eas e o segundo, alem\u00e3o. Jaguar e Porsche utilizam receitas &#8230;<\/p>\n","protected":false},"author":30,"featured_media":16538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9,299],"tags":[2728,2727,2726,1306],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/16558"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=16558"}],"version-history":[{"count":2,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/16558\/revisions"}],"predecessor-version":[{"id":16563,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/16558\/revisions\/16563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/16538"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=16558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=16558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=16558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}