{"id":15364,"date":"2017-07-28T12:19:50","date_gmt":"2017-07-28T12:19:50","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=15364"},"modified":"2017-07-28T12:19:50","modified_gmt":"2017-07-28T12:19:50","slug":"palavra-do-presidente-28072017","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/palavra-do-presidente-28072017\/","title":{"rendered":"Palavra do Presidente 28\/07\/2017"},"content":{"rendered":"<p><strong>elogio e cr\u00edtica<\/strong><\/p>\n<p>O elogio da semana vai para o prefeito Nilson Gaspar pela atitude de entrar com um processo de caducidade para que o contrato com o grupo VB Transportes possa ser rescindido, isso devido \u00e0 inadimpl\u00eancia e descumprimento de cl\u00e1usulas contratuais cometidas pela empresa em rela\u00e7\u00e3o ao Transporte P\u00fablico da cidade.<\/p>\n<p>A cr\u00edtica, por sua vez, vai para o grupo VB Transportes por n\u00e3o cumprir com as cl\u00e1usulas contratuais e como consequ\u00eancia prejudicar os usu\u00e1rios do Transporte P\u00fablico na cidade, que muitas vezes, n\u00e3o possuem outra op\u00e7\u00e3o.<\/p>\n<p>Nota 1<br \/>\nEsta semana o Servi\u00e7o Aut\u00f4nomo de \u00c1gua e Esgotos (Saae) est\u00e1 finalizando a interliga\u00e7\u00e3o do novo reservat\u00f3rio apoiado, localizado no Jardim Regente (Centro de Reserva\u00e7\u00e3o Regente) com a Esta\u00e7\u00e3o de Tratamento de \u00c1gua localizada na Vila Ava\u00ed (ETA I), e d\u00e1 in\u00edcio aos testes de estanqueidade no novo reservat\u00f3rio apoiado do Centro de Reserva\u00e7\u00e3o do Buru, no Parque Campo Bonito. O teste de estanqueidade, que est\u00e1 sendo executado no CR Buru, consiste em encher o reservat\u00f3rio com um metro de \u00e1gua por dia at\u00e9 atingir sua altura total, \u00e9 um processo necess\u00e1rio para localizar vazamentos nos novos reservat\u00f3rios. Assim que totalmente interligado, ser\u00e1 a vez do CR Regente passar pelo teste.<\/p>\n<p>nota 2<br \/>\nA Prefeitura concretou ter\u00e7a-feira (25) a base da quadra poliesportiva que ir\u00e1 compor o Sistema de Lazer da \u00e1rea em urbaniza\u00e7\u00e3o no loteamento Colinas de Indaiatuba I. Toda a parte de prepara\u00e7\u00e3o do solo, cal\u00e7amento e os dois lagos da \u00e1rea j\u00e1 est\u00e3o prontos. A previs\u00e3o \u00e9 de que a obra esteja conclu\u00edda at\u00e9 outubro. Na pr\u00f3xima semana a Secretaria de Urbanismo e do Meio Ambiente deve preparar a base para a instala\u00e7\u00e3o dos equipamentos de uma Academia da Terceira Idade e tamb\u00e9m de um playground no local. O espa\u00e7o tamb\u00e9m ter\u00e1 um campo de futebol gramado, pista de caminhada, paisagismo e toda a ilumina\u00e7\u00e3o necess\u00e1ria.<\/p>\n<p>nota 3<br \/>\nAs inscri\u00e7\u00f5es gratuitas para o projeto Esporte Cidad\u00e3o ser\u00e3o realizadas no dia 5 de agosto, das 8h \u00e0s 14h, nos N\u00facleos Esportivos. Ser\u00e3o abertas as inscri\u00e7\u00f5es para as vagas remanescentes de alunos desistentes do 1\u00ba semestre de 2017. Para se inscrever, o aluno deve comparecer em um dos N\u00facleos Esportivos acompanhado dos pais ou respons\u00e1vel, apresentar o RG e o comprovante de resid\u00eancia e preencher a ficha de inscri\u00e7\u00e3o dispon\u00edvel no local.<\/p>\n<p>Confira abaixo os n\u00facleos esportivos e as modalidades do Esporte Cidad\u00e3o:<\/p>\n<p>1. CRAS V<br \/>\nRua Louren\u00e7o Martins do Amaral, 241 \u2013 Jardim Brasil.<br \/>\nTelefone: 3825-2065<br \/>\nModalidades: Futebol e Recrea\u00e7\u00e3o Esportiva<\/p>\n<p>2. Arena Aldrovandi<br \/>\nAv. \u00c2ngelo Berteli Neto, 1000 \u2013 Jardim Carlos Aldrovandi<br \/>\nTelefone: 3816-6819<br \/>\nModalidades: Futsal, Gin\u00e1stica Art\u00edstica, Gin\u00e1stica R\u00edtmica e Geral.<\/p>\n<p>3. Associa\u00e7\u00e3o Amigos de Bairro XII de Junho<br \/>\nRua Padre Francisco de Paula Cabral de Vasconcellos, 786 Jardim Morada do Sol<br \/>\nTelefone: 3936-6595<br \/>\nModalidades: Futsal<\/p>\n<p>4. Educando Para a Vida<br \/>\nRua Jo\u00e3o Canova, 421 \u2013 Jd. Lauro Bueno<br \/>\nTelefone: 3834-1697<br \/>\nModalidades: Futsal, Voleibol e Recrea\u00e7\u00e3o Esportiva<\/p>\n<p>5. Campo do Oliveira Camargo<br \/>\nRua Manoel F. Ribeiro Garcia, s\/n\u00ba \u2013 Jardim Oliveira Camargo<br \/>\nModalidades: Futebol, Futsal e Handebol.<\/p>\n<p>6. Campo do S\u00e3o Conrado<br \/>\nRua Jos\u00e9 de Campos, s\/n\u00ba \u2013 Jardim S\u00e3o Conrado<br \/>\nModalidade: Futebol.<\/p>\n<p>7. Centro de Gin\u00e1stica<br \/>\nRua Guatemala, 147 \u2013 Parque Boa Esperan\u00e7a<br \/>\nTelefone: 3816-6892<br \/>\nModalidades: Taekwondo, Jud\u00f4 e Gin\u00e1stica Art\u00edstica.<\/p>\n<p>8. Centro Esportivo Calif\u00f3rnia<br \/>\nRua Ema Montoanelli Tachinard s\/n\u00ba \u2013 Jardim Calif\u00f3rnia<br \/>\nTelefone: 3835-3765<br \/>\nModalidades: Nata\u00e7\u00e3o e Futebol<\/p>\n<p>9. Centro Esportivo do Trabalhador<br \/>\nAv. Concei\u00e7\u00e3o, 1885 \u2013 Cidade Nova.<br \/>\nTelefones: 3894-3604 \/ 3894-3015<br \/>\nModalidades: Futebol, Futsal, Handebol, Voleibol, Basquetebol, Atletismo, Nata\u00e7\u00e3o, Recrea\u00e7\u00e3o Esportiva e Capoeira.<\/p>\n<p>10. Centro Esportivo R\u00eamulo Zoppi<br \/>\nRua Helena Tomasi, 53 \u2013 Jardim R\u00eamulo Zoppi<br \/>\nTelefone: 3816-5921<br \/>\nModalidades: Nata\u00e7\u00e3o, Futebol.<\/p>\n<p>11. Gin\u00e1sio Municipal de Esportes<br \/>\nAv. Visconde de Indaiatuba, 1250 \u2013 Jardim Am\u00e9rica<br \/>\nTelefone: 3825-6270<br \/>\nModalidades: Gin\u00e1stica R\u00edtmica.<\/p>\n<p>12. Centro de Lutas Jo\u00e3o Pioli<br \/>\nRua Ant\u00f4nio Magnusson, 82 \u2013 Jardim Morada do Sol<br \/>\nModalidades: Jud\u00f4, Carat\u00ea, Taekwondo e Jiu Jitsu.<\/p>\n<p>13. Parque Corolla<br \/>\nRua Serafim Gilberto Candello, s\/n\u00ba \u2013 Jardim Morada do Sol<br \/>\nTelefone: 3936-3301<br \/>\nModalidades: Futsal, Basquetebol, Capoeira, Carat\u00ea, Voleibol, Jiu Jitsu, Recrea\u00e7\u00e3o Esportiva, Nata\u00e7\u00e3o.<\/p>\n<p>14. Pista de Bicicross<br \/>\nAv. Eng. F\u00e1bio Roberto Barnab\u00e9, s\/n\u00ba \u2013 Jardim Esplanada<br \/>\nModalidades: Bicicross<\/p>\n<p>15. Quadra 23<br \/>\nRua Antonio Brunetti s\/n\u00ba Pra\u00e7a Darcy Barnab\u00e9 \u2013 Jardim Morada do Sol<br \/>\nTelefone: 3894-5763<br \/>\nModalidades: Gin\u00e1stica R\u00edtmica, Gin\u00e1stica Art\u00edstica e Gin\u00e1stica de Trampolim.<\/p>\n<p>16. Quadra de T\u00eanis do Parque Tem\u00e1tico<br \/>\nAv. Engenheiro Fabio Roberto Barnab\u00e9, s\/n\u00ba<br \/>\nModalidades: T\u00eanis.<\/p>\n<p>17. SESI<br \/>\nAv. Francisco de Paula Leite, 2701 \u2013 Jardim Calif\u00f3rnia.<br \/>\nTelefone: 3825-4650<br \/>\nModalidades: Atletismo, Nata\u00e7\u00e3o, Handebol, Futsal, Gin\u00e1stica R\u00edtmica e T\u00eanis.<\/p>\n<p>18. Centro de Esportes e Artes Unificados (CEU)<br \/>\nRua Jordalino Pietrobom, 1300 Jardim S\u00e3o Conrado<br \/>\nTelefones: 3936-5521 e 3935-9267<br \/>\nModalidade: Futsal<\/p>\n<p>nota 4<br \/>\nA interface entre a Doen\u00e7a de Alzheimer e outras condi\u00e7\u00f5es cl\u00ednicas ser\u00e1 o tema abordado na reuni\u00e3o mensal do Grupo de Apoio da Subregional de Indaiatuba da Associa\u00e7\u00e3o Brasileira de Alzheimer (Abraz), pela m\u00e9dica geriatra e presidente da entidade, Celene Queiroz Pinheiro de Oliveira. O encontro ser\u00e1 na segunda-feira, dia 7, \u00e0s 19 horas, na sede da Associa\u00e7\u00e3o Paulista de Medicina (APM), na Avenida Engenheiro F\u00e1bio Roberto Barnab\u00e9 (marginal do Parque Ecol\u00f3gico), 709, Vila Teller. A participa\u00e7\u00e3o \u00e9 gratuita e n\u00e3o \u00e9 necess\u00e1rio fazer pr\u00e9-inscri\u00e7\u00e3o. Mais informa\u00e7\u00f5es em: facebook.com\/abrazindaiatuba.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>elogio e cr\u00edtica O elogio da semana vai para o prefeito Nilson Gaspar pela atitude de entrar com um processo de caducidade para que o contrato com o grupo VB Transportes possa ser rescindido, isso devido \u00e0 inadimpl\u00eancia e descumprimento de cl\u00e1usulas contratuais cometidas pela empresa em rela\u00e7\u00e3o ao Transporte P\u00fablico da cidade. A cr\u00edtica, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":2699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[106],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/15364"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=15364"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/15364\/revisions"}],"predecessor-version":[{"id":15365,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/15364\/revisions\/15365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/2699"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=15364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=15364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=15364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}