{"id":12975,"date":"2017-03-10T13:15:29","date_gmt":"2017-03-10T13:15:29","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=12975"},"modified":"2017-03-10T13:15:29","modified_gmt":"2017-03-10T13:15:29","slug":"palavra-do-presidente-10032017","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/palavra-do-presidente-10032017\/","title":{"rendered":"Palavra do Presidente 10\/03\/2017"},"content":{"rendered":"<p><strong>Elogio e cr\u00edtica<\/strong><\/p>\n<p>O elogio da semana \u00e9 dedicado a todas as mulheres pelo Dia Internacional da Mulher. Que a for\u00e7a da delicadeza esteja sempre com voc\u00eas. E lembrando que a data n\u00e3o \u00e9 somente o 8 de mar\u00e7o, e sim todos os dias do ano.<\/p>\n<p>A cr\u00edtica vai aos motociclistas que abusam da habilidade no tr\u00e2nsito colocando em risco sua seguran\u00e7a. Cuidado e aten\u00e7\u00e3o redobrada nunca \u00e9 demais, preserve sua vida e a de seus semelhantes.<\/p>\n<div class=\"mom-members\" style=\"background-color:#ffe680;border-color:#cca300;color:#665200\">Conte\u00fado somente para assinantes. Por favor fa\u00e7a o login<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Elogio e cr\u00edtica O elogio da semana \u00e9 dedicado a todas as mulheres pelo Dia Internacional da Mulher. Que a for\u00e7a da delicadeza esteja sempre com voc\u00eas. E lembrando que a data n\u00e3o \u00e9 somente o 8 de mar\u00e7o, e sim todos os dias do ano. A cr\u00edtica vai aos motociclistas que abusam da habilidade &#8230;<\/p>\n","protected":false},"author":1,"featured_media":2699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[106],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/12975"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=12975"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/12975\/revisions"}],"predecessor-version":[{"id":12976,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/12975\/revisions\/12976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/2699"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=12975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=12975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=12975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}