{"id":11732,"date":"2016-12-02T11:03:26","date_gmt":"2016-12-02T11:03:26","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=11732"},"modified":"2016-12-02T11:03:26","modified_gmt":"2016-12-02T11:03:26","slug":"entrega-solene","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/entrega-solene\/","title":{"rendered":"Entrega solene"},"content":{"rendered":"<div class=\"mom_lightbox\"><a href=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2016\/12\/06-TL-encaixar.jpg\"><img src=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2016\/12\/06-TL-encaixar.jpg\" alt=\"img\"><span class=\"plus_overlay\"><i><\/i><\/span><\/a><\/div>\n<p>advogada Lenora Panzetti participando da Cerim\u00f4nia de Entrega Solene das Credenciais aos integrantes da Comiss\u00e3o Estadual de Direitos e Prerrogativas pelas m\u00e3os do Presidente da Seccional Paulista Dr. Marcos da Costa e do Presidente da Comiss\u00e3o, Dr. Cid Vieira Filho, na sede da OAB-SP, na tarde do dia 23 de novembro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>advogada Lenora Panzetti participando da Cerim\u00f4nia de Entrega Solene das Credenciais aos integrantes da Comiss\u00e3o Estadual de Direitos e Prerrogativas pelas m\u00e3os do Presidente da Seccional Paulista Dr. Marcos da Costa e do Presidente da Comiss\u00e3o, Dr. Cid Vieira Filho, na sede da OAB-SP, na tarde do dia 23 de novembro<\/p>\n","protected":false},"author":1,"featured_media":11733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[2070,38],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/11732"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=11732"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/11732\/revisions"}],"predecessor-version":[{"id":11734,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/11732\/revisions\/11734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/11733"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=11732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=11732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=11732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}