{"id":11520,"date":"2016-11-25T04:29:10","date_gmt":"2016-11-25T04:29:10","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=11520"},"modified":"2016-11-24T11:31:49","modified_gmt":"2016-11-24T11:31:49","slug":"destaque-da-tv-fechada-25112016","status":"publish","type":"post","link":"https:\/\/www.jornalexemplo.com.br\/jornal\/destaque-da-tv-fechada-25112016\/","title":{"rendered":"Destaque da TV Fechada 25\/11\/2016"},"content":{"rendered":"<p>SEXTA-FEIRA, 25\/11<\/p>\n<p>Um her\u00f3i de brinquedo<br \/>\nPara se redimir com o filho, um pai promete lhe dar um boneco do Turbo Man. Por\u00e9m, \u00e0s v\u00e9speras do Natal, o brinquedo est\u00e1 esgotado em todas as lojas. Determinado a cumprir a promessa, ele n\u00e3o n\u00e3o mede esfor\u00e7os para conseguir o presente, mesmo que isso signifique brigar com outro pai na mesma miss\u00e3o. \u00c0s 12h30 no Megapix.<\/p>\n<p>ULTRAVIOLETA<br \/>\nEm ritmo de hist\u00f3ria em quadrinhos, esta aventura futurista se passa no fim do s\u00e9culo 21, quando uma doen\u00e7a rara acomete um grupo de humanos, tornando-os extremamente velozes, inteligentes e fortes. Obrigados a viver longe da sociedade, eles logo ter\u00e3o de enfrentar uma guerra civil, j\u00e1 que representam uma amea\u00e7a \u00e0 esp\u00e9cie humana. No centro de tudo est\u00e1 Violet (Milla Jovovich), uma mulher infectada que dever\u00e1 defender a vida de um garoto marcado para morrer. \u00c0s 17h29 no Space.<\/p>\n<p>Guerra Dos Mundos<br \/>\nUm ataque alien\u00edgena surpresa faz com que Ray Ferrier precise cuidar de seus filhos, mesmo sem saber direito como fazer isso. \u00c0s 23h10 no Universal Channel.<\/p>\n<p>S\u00e1bado, 26\/11<\/p>\n<p>Invas\u00e3o Do Mundo: Batalha De Los Angeles<br \/>\nA Terra \u00e9 atacada por alien\u00edgenas que almejam acabar com a vida humana. O esquadr\u00e3o da Marinha norte-americana re\u00fane toda a sua frota para deter a invas\u00e3o inimiga. \u00c0s 9h40 no Universal Channel.<\/p>\n<p>Professor peso pesado<br \/>\nScott \u00e9 um professor de biologia que tenta impedir que a escola onde leciona deixe de oferecer uma disciplina eletiva que julga importante. Para isso ele decide se tornar um lutador de artes marciais para conseguir juntar uma boa quantia de dinheiro e ajudar o col\u00e9gio. \u00c0s 17h55 no Megapix.<\/p>\n<p>A M\u00famia<br \/>\nNos anos 20, Rick O\u2019Connell, a arque\u00f3loga Evelyn e seu irm\u00e3o buscam o lend\u00e1rio tesouro do fara\u00f3. Mas, ao entrarem na tumba do sacerdote Imhotep, eles o trazem de volta \u00e0 vida, libertando sua ira. \u00c0s 23h10 no Universal Channel.<\/p>\n<p>DOMINGO, 27\/11<\/p>\n<p>Sabrina<br \/>\nSabrina \u00e9 a filha do motorista de uma rica fam\u00edlia. Desde pequena, ela se encanta por um dos filhos dos patr\u00f5es. Depois de passar anos na Fran\u00e7a, ela volta transformada e encanta o rapaz por quem sempre fora apaixonada. Mas ele est\u00e1 noivo, e esse relacionamento pode afetar os interesses da fam\u00edlia. \u00c0s 11h30 no Megapix.<\/p>\n<p>R.I.P.D. &#8211; Agentes Do Al\u00e9m<br \/>\nUm policial recentemente assassinado se junta ao time de policias mortos-vivos e tenta encontrar o homem que o matou. \u00c0s 21h20 no Universal Channel.<\/p>\n<p>ATIRADOR<br \/>\nUm ex-atirador de elite (Mark Wahlberg) que vive isolado nas montanhas \u00e9 recrutado por um militar (Danny Glover, Jogos Mortais) para impedir um compl\u00f4 contra o presidente dos Estados Unidos. Ele aceita o servi\u00e7o, por\u00e9m, \u00e9 tra\u00eddo. Agora, precisa salvar sua vida e descobrir quem foi o traidor. \u00c0s 22h58 no Space.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SEXTA-FEIRA, 25\/11 Um her\u00f3i de brinquedo Para se redimir com o filho, um pai promete lhe dar um boneco do Turbo Man. Por\u00e9m, \u00e0s v\u00e9speras do Natal, o brinquedo est\u00e1 esgotado em todas as lojas. Determinado a cumprir a promessa, ele n\u00e3o n\u00e3o mede esfor\u00e7os para conseguir o presente, mesmo que isso signifique brigar com &#8230;<\/p>\n","protected":false},"author":1,"featured_media":11521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[51],"tags":[59],"_links":{"self":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/11520"}],"collection":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=11520"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/11520\/revisions"}],"predecessor-version":[{"id":11522,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/11520\/revisions\/11522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/11521"}],"wp:attachment":[{"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=11520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=11520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=11520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}