{"id":9429,"date":"2016-07-15T11:25:00","date_gmt":"2016-07-15T11:25:00","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=9429"},"modified":"2016-07-15T11:25:00","modified_gmt":"2016-07-15T11:25:00","slug":"ao-amigo-que-morreu","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/ao-amigo-que-morreu\/","title":{"rendered":"Ao amigo que morreu"},"content":{"rendered":"<p>Amigo Roberto Avelar. Faz anos que voc\u00ea partiu. N\u00e3o sei se estas not\u00edcias possam interess\u00e1-lo. Pouco me custa este rascunho que, t\u00e3o logo terminado, vou atir\u00e1-lo \u00e0 cesta de pap\u00e9is. Escrever \u00e9 um modo de eu matar o tempo que, agora aposentado, tenho de sobra para afugentar a solid\u00e3o que, teimosa procura conviver comigo \u00e0 medida que passam os anos e vamos perdendo os entes queridos. Engra\u00e7ado algu\u00e9m rodeado de parentes e amigos sentir solid\u00e3o! \u00c9 um estado de alma, quase inexplic\u00e1vel, e eu n\u00e3o tenho compet\u00eancia para desvend\u00e1-lo.<br \/>\nO mundo n\u00e3o mudou muito. Se mudou, foi para pior. \u00c9 quase o mesmo que voc\u00ea deixou em um acidente, \u00e0 noite, em deserta rodovia, sem dizer adeus \u00e0 fam\u00edlia e aos amigos. A maldade e a gan\u00e2ncia dos homens irrompem aos jorros, crescem e agigantam-se. Os poderosos aprimoram-se nas crueldades e buscam qualquer meio de enricar mais e mais \u00e0 custa do sofrimento e desgra\u00e7a alheios. Amor ao pr\u00f3ximo, caridade, belas palavras que se escrevem e ouvem h\u00e1 s\u00e9culos, sem nunca se cuidar de seu real significado. Os raros bons samaritanos vivem medrosos de ser descobertos. Praticam seus atos de benevol\u00eancia \u00e0s escondidas, como se cometessem o mais hediondo dos crimes.<\/p>\n<div class=\"mom-members\" style=\"background-color:#ffe680;border-color:#cca300;color:#665200\">Conte\u00fado somente para assinantes. Por favor fa\u00e7a o login<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Amigo Roberto Avelar. Faz anos que voc\u00ea partiu. N\u00e3o sei se estas not\u00edcias possam interess\u00e1-lo. Pouco me custa este rascunho que, t\u00e3o logo terminado, vou atir\u00e1-lo \u00e0 cesta de pap\u00e9is. Escrever \u00e9 um modo de eu matar o tempo que, agora aposentado, tenho de sobra para afugentar a solid\u00e3o que, teimosa procura conviver comigo \u00e0 &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[1651,104],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/9429"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=9429"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/9429\/revisions"}],"predecessor-version":[{"id":9430,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/9429\/revisions\/9430"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=9429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=9429"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=9429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}