{"id":7696,"date":"2016-04-01T12:06:01","date_gmt":"2016-04-01T12:06:01","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=7696"},"modified":"2016-04-01T12:06:01","modified_gmt":"2016-04-01T12:06:01","slug":"society-faz-4-jogos-no-domingo","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/society-faz-4-jogos-no-domingo\/","title":{"rendered":"Society faz 4 jogos no domingo"},"content":{"rendered":"<p>Depois da folga do \u00faltimo final de semana, motivada pelo feriado prolongado da P\u00e1scoa, as duas copas de futebol society do Indaiatuba Clube retornam neste domingo, dia 3 de abril, com quatro jogos. Essas partidas v\u00e3o fechar a disputa da terceira rodada que come\u00e7ou no dia 20 de mar\u00e7o com a realiza\u00e7\u00e3o de tr\u00eas jogos.<br \/>\nA partir das 8h, pela Copa Col\u00e9gio Renova\u00e7\u00e3o de Futebol Society \u2013 Categoria Veteranos, o HotFlowers encara o Marquinhos Tinhas. Na sequ\u00eancia, a partir das 9h10 o Cl\u00ednica S\u00e3o Camilo joga contra o BrasilTex.<br \/>\nLogo depois, por volta das 10h15 acontecem os dois jogos da Copa HotFlowers de Futebol Society \u2013 Categoria Adulto, quando o Imp\u00e9rio enfrenta o Estilo Som &amp; Luz. Fechando o dia, \u00e0s 11h20 o Cria Filmes encara o Verona Restaurante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois da folga do \u00faltimo final de semana, motivada pelo feriado prolongado da P\u00e1scoa, as duas copas de futebol society do Indaiatuba Clube retornam neste domingo, dia 3 de abril, com quatro jogos. Essas partidas v\u00e3o fechar a disputa da terceira rodada que come\u00e7ou no dia 20 de mar\u00e7o com a realiza\u00e7\u00e3o de tr\u00eas jogos. &#8230;<\/p>\n","protected":false},"author":1,"featured_media":7697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[264],"tags":[40],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7696"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=7696"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7696\/revisions"}],"predecessor-version":[{"id":7698,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/7696\/revisions\/7698"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/7697"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=7696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=7696"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=7696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}