{"id":4420,"date":"2015-10-02T11:14:00","date_gmt":"2015-10-02T11:14:00","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=4420"},"modified":"2015-10-02T11:14:00","modified_gmt":"2015-10-02T11:14:00","slug":"natacao-pcd-garante-recordes-e-medalhas-no-global-games","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/natacao-pcd-garante-recordes-e-medalhas-no-global-games\/","title":{"rendered":"Nata\u00e7\u00e3o PCD garante recordes e medalhas no Global Games"},"content":{"rendered":"<p>A equipe de nata\u00e7\u00e3o PCD ADI\/Secretaria Municipal de Esportes alcan\u00e7ou novas conquistas para o munic\u00edpio, desta vez com a participa\u00e7\u00e3o do atleta Felipe Caltran no Global Games, evento promovido pela International Federation for Sport for Athletes with an Intellectual Impairment (Inas) de 20 a 25 de setembro em Guayaquil, no Equador. O nadador de Indaiatuba conquistou cinco medalhas, sendo duas ouro, duas prata e uma bronze, al\u00e9m de bater sete recordes brasileiros \u2013 quatro individuais e tr\u00eas em revezamentos \u2013 e um recorde mundial nos 50m livre. \u201cMesmo sendo um evento desgastante, onde foi suprimido um dia de descanso programado por problemas da organiza\u00e7\u00e3o, Felipe volta mais estruturado fisicamente e vai se tornando um atleta maduro, capaz, em um futuro pr\u00f3ximo, de trazer grandes alegrias no programa paraol\u00edmpico\u201d, comenta o t\u00e9cnico Ant\u00f4nio Luiz C\u00e2ndido. \u201cNo programa adotado pelo Comit\u00ea Paral\u00edmpico, os atletas com defici\u00eancia intelectual tiveram provas restritas. Para Felipe garantir uma vaga, precisa melhorar suas marcas nas provas de 200m livre, onde hoje \u00e9 o 12\u00ba no ranking mundial, e nos 200m medley, onde \u00e9 o 19\u00ba. Continuamos com os treinos focados no objetivo de conquistar uma vaga nos Jogos Paral\u00edmpicos de 2016\u201d, finaliza.<\/p>\n<p>&nbsp;<\/p>\n<p>Resultados:<\/p>\n<p>200m livre \u2013 recorde brasileiro com 2\u201902\u201d49, 12\u00ba tempo no ranking mundial e 4\u00ba lugar na final;<\/p>\n<p>400m medley \u2013 recorde brasileiro com 5\u201902\u201d77, 2\u00ba tempo no ranking mundial e medalha de prata;<\/p>\n<p>200m borboleta \u2013 recorde brasileiro com 2\u201923\u201d82, 2\u00ba tempo no ranking mundial e medalha de ouro;<\/p>\n<p>200m medley \u2013 29\u00ba tempo no ranking mundial (2\u201923\u201d39) e 7\u00ba lugar na prova;<\/p>\n<p>100m livre \u2013 recorde brasileiro com 56\u201d87, 9\u00ba tempo no ranking mundial e medalha de bronze no Revezamento 4x100m livre;<\/p>\n<p>50m livre \u2013 medalha de prata no Revezamento 4 x 50m medley e medalha de ouro com 5x50m livre, com recorde mundial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A equipe de nata\u00e7\u00e3o PCD ADI\/Secretaria Municipal de Esportes alcan\u00e7ou novas conquistas para o munic\u00edpio, desta vez com a participa\u00e7\u00e3o do atleta Felipe Caltran no Global Games, evento promovido pela International Federation for Sport for Athletes with an Intellectual Impairment (Inas) de 20 a 25 de setembro em Guayaquil, no Equador. O nadador de Indaiatuba &#8230;<\/p>\n","protected":false},"author":17,"featured_media":4423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[264,4],"tags":[],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/4420"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=4420"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/4420\/revisions"}],"predecessor-version":[{"id":4424,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/4420\/revisions\/4424"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/4423"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=4420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=4420"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=4420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}