{"id":4241,"date":"2015-09-25T12:47:20","date_gmt":"2015-09-25T12:47:20","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=4241"},"modified":"2015-09-25T12:47:20","modified_gmt":"2015-09-25T12:47:20","slug":"secretaria-de-cultura-abre-inscricoes-para-novas-oficinas-gratuitas","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/secretaria-de-cultura-abre-inscricoes-para-novas-oficinas-gratuitas\/","title":{"rendered":"Secretaria de Cultura abre inscri\u00e7\u00f5es para novas oficinas gratuitas"},"content":{"rendered":"<p>A Secretaria Municipal de Cultura abre no dia 1\u00ba de outubro, no Centro de Conven\u00e7\u00f5es Aydil Bonachella, as inscri\u00e7\u00f5es para quatro novas oficinas culturais gratuitas: Edi\u00e7\u00e3o e Publica\u00e7\u00e3o Autoral de Quadrinhos, ministrada por Delfin; T\u00e9cnicas de Desenho Hiper Realista, por Walter Caldeira; Projeto C\u00e2mera Clara, que engloba oficina de pinhole (c\u00e2mera sem lente) e exposi\u00e7\u00e3o das fotografias realizadas no workshop, com o grupo Jatob\u00e1 Cultural; e Roteiro de Novelas, com Alessandro Marson. As vagas s\u00e3o limitadas e as ades\u00f5es podem ser realizadas de segunda a sexta, das 8h \u00e0s 12h e das 13h \u00e0s 17h, seguindo as diretrizes e apresenta\u00e7\u00e3o de documenta\u00e7\u00e3o de cada oficina, conforme abaixo. Informa\u00e7\u00f5es (19) 3894-1867.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal de Cultura abre no dia 1\u00ba de outubro, no Centro de Conven\u00e7\u00f5es Aydil Bonachella, as inscri\u00e7\u00f5es para quatro novas oficinas culturais gratuitas: Edi\u00e7\u00e3o e Publica\u00e7\u00e3o Autoral de Quadrinhos, ministrada por Delfin; T\u00e9cnicas de Desenho Hiper Realista, por Walter Caldeira; Projeto C\u00e2mera Clara, que engloba oficina de pinhole (c\u00e2mera sem lente) e exposi\u00e7\u00e3o &#8230;<\/p>\n","protected":false},"author":17,"featured_media":4242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,262],"tags":[],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/4241"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=4241"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/4241\/revisions"}],"predecessor-version":[{"id":4243,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/4241\/revisions\/4243"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/4242"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=4241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=4241"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=4241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}