{"id":37575,"date":"2025-11-28T09:34:41","date_gmt":"2025-11-28T09:34:41","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=37575"},"modified":"2025-11-28T09:34:45","modified_gmt":"2025-11-28T09:34:45","slug":"cantavento-traz-oficina-e-espetaculo-para-a-cidade","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/cantavento-traz-oficina-e-espetaculo-para-a-cidade\/","title":{"rendered":"CantaVento traz oficina e espet\u00e1culo para a cidade"},"content":{"rendered":"\n<p>A Prefeitura Municipal de Indaiatuba, por meio da Secretaria Municipal de Cultura, recebe neste pr\u00f3ximo domingo, 30 de novembro, no Casar\u00e3o Pau Preto, o grupo CantaVento para uma manh\u00e3 totalmente dedicada \u00e0s crian\u00e7as e \u00e0s fam\u00edlias. A programa\u00e7\u00e3o especial inclui a oficina M\u00fasica e Quintais de Dentro, \u00e0s 9h30, e, na sequ\u00eancia, \u00e0s 11h, o espet\u00e1culo musical Quintais de Dentro.<br>As inscri\u00e7\u00f5es para a oficina, destinada a crian\u00e7as de 7 a 12 anos, abrem hoje (25\/11), \u00e0s 12h, pelo link: https:\/\/forms.gle\/KHqv8fuLUvngC4Jg8. S\u00e3o 30 vagas gratuitas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/11\/catavento.png\"><img width=\"1024\" height=\"663\" src=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/11\/catavento-1024x663.png\" alt=\"\" class=\"wp-image-37576\" srcset=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/11\/catavento-1024x663.png 1024w, http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/11\/catavento-300x194.png 300w, http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/11\/catavento-768x497.png 768w, http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/11\/catavento.png 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Programa\u00e7\u00e3o<\/strong><br>O espet\u00e1culo Quintais de Dentro \u00e9 um convite do grupo CantaVento para o p\u00fablico a explorar os \u201cquintais internos\u201d, espa\u00e7os simb\u00f3licos que cada pessoa carrega dentro de si. Inspirado em manifesta\u00e7\u00f5es como samba de len\u00e7o, cururu, jongo, coco, bumba-meu-boi e moda de viola, o espet\u00e1culo cria uma atmosfera intimista e afetuosa, que valoriza a escuta e o acolhimento. A apresenta\u00e7\u00e3o re\u00fane m\u00fasica de c\u00e2mara, performance corporal, literatura, conta\u00e7\u00e3o de hist\u00f3rias e forte intera\u00e7\u00e3o com o p\u00fablico, sendo especialmente indicada para crian\u00e7as que se beneficiam de experi\u00eancias culturais sens\u00edveis e delicadas. Dura\u00e7\u00e3o: 50 minutos.<\/p>\n\n\n\n<p>O<strong>ficina<\/strong><br>J\u00e1 a oficina M\u00fasica e Quintais de Dentro, prop\u00f5e um encontro musical com cantos, percuss\u00e3o corporal, brincadeiras cantadas e improvisa\u00e7\u00e3o, incentivando a express\u00e3o dos sentimentos e a constru\u00e7\u00e3o de rela\u00e7\u00f5es saud\u00e1veis por meio da m\u00fasica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura Municipal de Indaiatuba, por meio da Secretaria Municipal de Cultura, recebe neste pr\u00f3ximo domingo, 30 de novembro, no Casar\u00e3o Pau Preto, o grupo CantaVento para uma manh\u00e3 totalmente dedicada \u00e0s crian\u00e7as e \u00e0s fam\u00edlias. A programa\u00e7\u00e3o especial inclui a oficina M\u00fasica e Quintais de Dentro, \u00e0s 9h30, e, na sequ\u00eancia, \u00e0s 11h, o &#8230;<\/p>\n","protected":false},"author":34,"featured_media":37576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,262],"tags":[],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/37575"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=37575"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/37575\/revisions"}],"predecessor-version":[{"id":37577,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/37575\/revisions\/37577"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/37576"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=37575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=37575"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=37575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}