{"id":36621,"date":"2025-04-11T10:07:43","date_gmt":"2025-04-11T10:07:43","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=36621"},"modified":"2025-04-11T10:08:14","modified_gmt":"2025-04-11T10:08:14","slug":"programa-familia-acolhedora-completa-3-anos","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/programa-familia-acolhedora-completa-3-anos\/","title":{"rendered":"Programa Fam\u00edlia Acolhedora completa 3 anos"},"content":{"rendered":"\n<p>A Prefeitura de Indaiatuba em parceria com a Associa\u00e7\u00e3o Beneficente Abid, Organiza\u00e7\u00e3o da Sociedade Civil (OSC), tem o Programa Fam\u00edlia Acolhedora &#8211; Projeto Moradas, com o objetivo de oferecer prote\u00e7\u00e3o integral a crian\u00e7as e adolescentes, que necessitam de afastamento tempor\u00e1rio da fam\u00edlia de origem, por medida de prote\u00e7\u00e3o. Durante o per\u00edodo de acolhimento, as equipes de apoio social e psicol\u00f3gico atuam tamb\u00e9m com os familiares para preparar o poss\u00edvel retorno da conviv\u00eancia familiar.<\/p>\n\n\n\n<p><br>Para gerenciar e aplicar o programa, a Secretaria de Assist\u00eancia Social realizou chamamento p\u00fablico que teve como vencedora a Abid.<\/p>\n\n\n\n<p><br>A Lei 7.754 foi publicada em 30 de mar\u00e7o de 2022 e completou tr\u00eas anos em 2025. Neste per\u00edodo foram 180 inscri\u00e7\u00f5es recebidas, 18 fam\u00edlias foram capacitadas, 36 crian\u00e7as e jovens acolhidos e atualmente 11 fam\u00edlias est\u00e3o acolhendo.<br>\u00c0 Secretaria cabe a responsabilidade de fiscalizar e acompanhar a entidade conveniada com os benefici\u00e1rios, enquanto isso, o Poder Judici\u00e1rio promove o encaminhamento das crian\u00e7as e adolescentes.<br>A Abid realizar\u00e1 a triagem social dos interessados em participar como Fam\u00edlia Acolhedora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Indaiatuba em parceria com a Associa\u00e7\u00e3o Beneficente Abid, Organiza\u00e7\u00e3o da Sociedade Civil (OSC), tem o Programa Fam\u00edlia Acolhedora &#8211; Projeto Moradas, com o objetivo de oferecer prote\u00e7\u00e3o integral a crian\u00e7as e adolescentes, que necessitam de afastamento tempor\u00e1rio da fam\u00edlia de origem, por medida de prote\u00e7\u00e3o. Durante o per\u00edodo de acolhimento, as equipes &#8230;<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,249],"tags":[7792,281],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/36621"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=36621"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/36621\/revisions"}],"predecessor-version":[{"id":36622,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/36621\/revisions\/36622"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=36621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=36621"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=36621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}