{"id":36513,"date":"2025-03-21T12:53:59","date_gmt":"2025-03-21T12:53:59","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=36513"},"modified":"2025-03-21T12:54:05","modified_gmt":"2025-03-21T12:54:05","slug":"homem-com-h-um-filme-sobre-ney-matogrosso","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/homem-com-h-um-filme-sobre-ney-matogrosso\/","title":{"rendered":"&#8220;Homem com H&#8221;: um filme sobre Ney Matogrosso"},"content":{"rendered":"\n<p>A cinebiografia \u201cHomem com H\u201d abordar\u00e1 diferentes fases da carreira de Ney Matogrosso &#8211; um dos mais relevantes artistas da Cultura brasileira. O longa-metragem revive a sua inf\u00e2ncia, passando pela adolesc\u00eancia e a vida adulta. A produ\u00e7\u00e3o acompanha um rapaz de origem humilde apaixonado pela natureza, que se liberta das opress\u00f5es e figuras de autoridade, quebra preconceitos e se torna um das pessoas mais influentes de sua gera\u00e7\u00e3o.<br>No elenco est\u00e3o Jesu\u00edta Barbosa (Praia do Futuro), Jullio Reis (S.O.S. Mulheres ao Mar 2), Bruno Montaleone (O Lado Bom de Ser Tra\u00edda) , R\u00f4mulo Braga (DNA do Crime), Hermila Guedes (Irmandade), Mauro Soares (Ant\u00f3nio Um Dois Tr\u00eas), Jeff Lyrio (Nina e o Abismo), Carol Abras (Vale dos Esquecidos) e Lara Tremoroux (Medusa), entre outros.<\/p>\n\n\n\n<p>Hist\u00f3ria<br>Ney Matogrosso iniciou sua trajet\u00f3ria na m\u00fasica na d\u00e9cada de 1970. \u00c9 conhecido por suas can\u00e7\u00f5es e dan\u00e7as irreverentes, por sua apar\u00eancia andr\u00f3gina e \u00e9 um dos artistas mais aut\u00eanticos da nossa hist\u00f3ria recente. Lan\u00e7ou can\u00e7\u00f5es de sucesso como, justamente, \u201cHomem com H\u201d e \u201cPoema\u201d. E o sucesso, quase imensur\u00e1vel, que o al\u00e7ou ao estrelato, aconteceu quando Ney aceitou ser o vocalista da banda \u201cSecos &amp; Molhados\u201d. O primeiro disco do grupo foi um verdadeiro \u2018arrasa quarteir\u00e3o\u2019 com can\u00e7\u00f5es ic\u00f4nicas como \u201cSangue Latino\u201d, \u201cO Vira\u201d e \u201cRosa de Hiroshima\u201d.<\/p>\n\n\n\n<p>Quando?<br>Em sua biografia, Ney Matogrosso fala sobre a dif\u00edcil conviv\u00eancia com seu pai, o militar Antonio Matogrosso Pereira. Descrito como \u201cconservador e cabe\u00e7a-dura\u201d, seu pai tinha pavor de qualquer manifesta\u00e7\u00e3o art\u00edstica que Ney pudesse desenvolver. O relacionamento conturbado entre eles durou at\u00e9 a adolesc\u00eancia, com Ney afirmando: \u201cEu odiava meu pai, meu pai me odiava\u201d. Anos depois, com Ney j\u00e1 adulto e artista, a rela\u00e7\u00e3o deles mudou.<br>At\u00e9 o momento, a distribuidora Paris Filmes ainda n\u00e3o divulgou qual a data exata do lan\u00e7amento de \u201cHomem com H\u201d nos cinemas brasileiros. No entanto, ela revelou que o t\u00edtulo tem sua estreia marcada ainda para 2025.<br>Ney Matogrosso, ele mesmo, \u00e9 um dos produtores da cinebiografia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/03\/homem-h.jpg\"><img width=\"882\" height=\"496\" src=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/03\/homem-h.jpg\" alt=\"\" class=\"wp-image-36514\" srcset=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/03\/homem-h.jpg 882w, http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/03\/homem-h-300x169.jpg 300w, http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2025\/03\/homem-h-768x432.jpg 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/a><figcaption>Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A cinebiografia \u201cHomem com H\u201d abordar\u00e1 diferentes fases da carreira de Ney Matogrosso &#8211; um dos mais relevantes artistas da Cultura brasileira. O longa-metragem revive a sua inf\u00e2ncia, passando pela adolesc\u00eancia e a vida adulta. A produ\u00e7\u00e3o acompanha um rapaz de origem humilde apaixonado pela natureza, que se liberta das opress\u00f5es e figuras de autoridade, &#8230;<\/p>\n","protected":false},"author":34,"featured_media":36514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[262],"tags":[],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/36513"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=36513"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/36513\/revisions"}],"predecessor-version":[{"id":36515,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/36513\/revisions\/36515"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/36514"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=36513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=36513"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=36513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}