{"id":33786,"date":"2021-09-17T13:11:07","date_gmt":"2021-09-17T13:11:07","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=33786"},"modified":"2021-09-17T13:11:13","modified_gmt":"2021-09-17T13:11:13","slug":"imagem-da-semana-17-9-2021","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/imagem-da-semana-17-9-2021\/","title":{"rendered":"Imagem da Semana 17\/9\/2021"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/09\/02-imagem-da-semana-scaled.jpg\"><img width=\"1024\" height=\"683\" src=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/09\/02-imagem-da-semana-1024x683.jpg\" alt=\"\" class=\"wp-image-33769\" srcset=\"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/09\/02-imagem-da-semana-1024x683.jpg 1024w, http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/09\/02-imagem-da-semana-300x200.jpg 300w, http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/09\/02-imagem-da-semana-768x512.jpg 768w, http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/09\/02-imagem-da-semana-1536x1024.jpg 1536w, http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/09\/02-imagem-da-semana-2048x1365.jpg 2048w, http:\/\/www.jornalexemplo.com.br\/jornal\/wp-content\/uploads\/2021\/09\/02-imagem-da-semana-765x510.jpg 765w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption><strong><em>Vacina\u00e7\u00e3o<\/em><\/strong> Indaiatuba comemora o registro de 50% da popula\u00e7\u00e3o estimada do munic\u00edpio com o esquema vacinal contra Covid-19 completo. No in\u00edcio da tarde desta quarta-feira (15) o Vacin\u00f4metro da Secretaria Municipal de Sa\u00fade atingiu a marca de 123.485 pessoas com as duas doses do imunizante e outras 6.860 vacinas de dose \u00fanica aplicadas, totalizando 130.345 mun\u00edcipes com imuniza\u00e7\u00e3o completa.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"Vacina\u00e7\u00e3o Indaiatuba comemora o registro de 50% da popula\u00e7\u00e3o estimada do munic\u00edpio com o esquema vacinal contra Covid-19 completo. No in\u00edcio da tarde desta quarta-feira (15) o Vacin\u00f4metro da Secretaria Municipal de Sa\u00fade atingiu a marca de 123.485 pessoas com as duas doses do imunizante e outras 6.860 vacinas de dose \u00fanica aplicadas, totalizando 130.345 ...","protected":false},"author":34,"featured_media":33769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[38,281],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/33786"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=33786"}],"version-history":[{"count":2,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/33786\/revisions"}],"predecessor-version":[{"id":33788,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/33786\/revisions\/33788"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/33769"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=33786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=33786"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=33786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}