{"id":3317,"date":"2015-08-14T14:07:59","date_gmt":"2015-08-14T14:07:59","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=3317"},"modified":"2015-08-14T14:07:59","modified_gmt":"2015-08-14T14:07:59","slug":"alunos-da-fiec-ficam-em-segundo-lugar-na-cometicao-da-cisco","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/alunos-da-fiec-ficam-em-segundo-lugar-na-cometicao-da-cisco\/","title":{"rendered":"Alunos da Fiec ficam em segundo lugar na Cometi\u00e7\u00e3o da Cisco"},"content":{"rendered":"<p>A Prefeitura de Indaiatuba e a Funda\u00e7\u00e3o Indaiatubana de Educa\u00e7\u00e3o e Cultura (Fiec) prestaram nesta ter\u00e7a-feira (11), no gabinete do prefeito Reinaldo Nogueira, uma homenagem aos alunos do curso t\u00e9cnico em Tecnologia da Informa\u00e7\u00e3o Maria Gabriela Santiago (2\u00ba), Lucca Ecclissi (81\u00ba) e Lucas Castro (97\u00b0), pela participa\u00e7\u00e3o na Competi\u00e7\u00e3o de Habilidades de IT Essentials para pa\u00edses da Am\u00e9rica Latina e Caribe 2015, ocorrida em julho, da Cisco Networking Academy NetRiders.<\/p>\n<p>De 121 classificados, oito brasileiros conseguiram coloca\u00e7\u00e3o, sendo tr\u00eas alunos da Fiec. Em agradecimento pelo resultado obtido, o prefeito entregou as placas aos participantes, firmando a significativa presen\u00e7a de Indaiatuba e do Brasil. Destaque para aluna Maria Gabriela Santiago, que conquistou o 2\u00ba lugar na competi\u00e7\u00e3o e foi selecionada com uma das maiores pontua\u00e7\u00f5es de desempenho. O pr\u00eamio \u00e9 um voucher de certifica\u00e7\u00e3o do IT Essentials, no valor de US$295,00 para realiza\u00e7\u00e3o da certifica\u00e7\u00e3o internacional Comptia A+ de abrang\u00eancia global, confirmando e reconhecendo os melhores talentos, aumentando as perspectivas da carreira.<\/p>\n<p>O superintendente Jo\u00e3o Neto parabenizou os alunos pela conquista e o prefeito frisou a import\u00e2ncia de aproveitar as oportunidades oferecidas aos jovens de Indaiatuba.<\/p>\n<p>Maria Gabriela Santiago, Lucca Ecclissi e Lucas Castro permanecer\u00e3o no ranking da Cisco, que \u00e9 refer\u00eancia no mercado mundial.<\/p>\n<p>&nbsp;<\/p>\n<p>Sobre a Competi\u00e7\u00e3o<\/p>\n<p>A competi\u00e7\u00e3o foi individual e consistia de dois momentos: o \u2018per\u00edodo de inscri\u00e7\u00e3o\u2019 que tratou de uma prova online com 75 perguntas para ser conclu\u00edda em at\u00e9 60 minutos e uma prova de habilidades pr\u00e1ticas com dez perguntas. As provas foram realizadas na Academia Cisco na Fiec, no formato online.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Indaiatuba e a Funda\u00e7\u00e3o Indaiatubana de Educa\u00e7\u00e3o e Cultura (Fiec) prestaram nesta ter\u00e7a-feira (11), no gabinete do prefeito Reinaldo Nogueira, uma homenagem aos alunos do curso t\u00e9cnico em Tecnologia da Informa\u00e7\u00e3o Maria Gabriela Santiago (2\u00ba), Lucca Ecclissi (81\u00ba) e Lucas Castro (97\u00b0), pela participa\u00e7\u00e3o na Competi\u00e7\u00e3o de Habilidades de IT Essentials para &#8230;<\/p>\n","protected":false},"author":19,"featured_media":3320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,254],"tags":[],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/3317"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=3317"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/3317\/revisions"}],"predecessor-version":[{"id":3322,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/3317\/revisions\/3322"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/3320"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=3317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=3317"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=3317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}