{"id":31869,"date":"2021-04-01T18:07:37","date_gmt":"2021-04-01T18:07:37","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=31869"},"modified":"2021-04-01T18:07:37","modified_gmt":"2021-04-01T18:07:37","slug":"sancionada-lei-que-aumenta-5-limite-de-consignado","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/sancionada-lei-que-aumenta-5-limite-de-consignado\/","title":{"rendered":"Sancionada lei que aumenta 5% limite de consignado"},"content":{"rendered":"<p><strong>Valor deve ser usado para saque e despesas com cart\u00e3o de cr\u00e9dito<\/strong><\/p>\n<p>O Presidente Jair Bolsonaro sancionou a lei que amplia de 35% para 40% margem de empr\u00e9stimo consignado para aposentados e pensionistas do Instituto Nacional do Seguro Social (INSS). O texto foi publicado ontem (31) no Di\u00e1rio Oficial da Uni\u00e3o .<\/p>\n<p>De acordo com a lei, 5% dos recursos consign\u00e1veis devem ser destinados exclusivamente para saque ou amortiza\u00e7\u00e3o de despesas do cart\u00e3o de cr\u00e9dito, um percentual j\u00e1 previsto. A medida vale para opera\u00e7\u00f5es contratadas at\u00e9 31 de dezembro de 2021. Ap\u00f3s esse prazo, as d\u00edvidas de consignado voltar\u00e3o ao patamar anterior, de at\u00e9 35% do sal\u00e1rio.<\/p>\n<p>A lei foi originada da Medida Provis\u00f3ria n\u00ba 1.006, de 2020, que aumentou temporariamente a margem do consignado at\u00e9 31 de dezembro de 2020. Ap\u00f3s modifica\u00e7\u00f5es feitas pelo Congresso, o prazo foi reaberto e prorrogado para 31 de dezembro de 2021.<\/p>\n<p>O cr\u00e9dito consignado \u00e9 aquele concedido com desconto autom\u00e1tico em folha de pagamento. Outra modifica\u00e7\u00e3o \u00e9 que, agora, a amplia\u00e7\u00e3o do percentual tamb\u00e9m poder\u00e1 ser aplicada para empr\u00e9stimos tomados por militares das For\u00e7as Armadas, policiais militares dos estados e do Distrito Federal, militares e policiais reformados, servidores p\u00fablicos estaduais e municipais, servidores p\u00fablicos inativos, empregados p\u00fablicos da administra\u00e7\u00e3o direta, aut\u00e1rquica e fundacional de qualquer ente da Federa\u00e7\u00e3o e pensionistas de servidores e de militares.<\/p>\n<p>Tamb\u00e9m foi aberta a possibilidade de os bancos aplicarem car\u00eancia de at\u00e9 120 dias para novas opera\u00e7\u00f5es de cr\u00e9dito consignado, mediante negocia\u00e7\u00e3o.<\/p>\n<p>Em nota, a Secretaria-Geral da Presid\u00eancia explicou que o objetivo da medida era possibilitar que benefici\u00e1rios do INSS tivessem maior acesso ao cr\u00e9dito consignado, modalidade que tem juros reais menores quando comparado a outras linhas de cr\u00e9dito dispon\u00edveis \u00e0s pessoas f\u00edsicas. \u201cA urg\u00eancia estaria vinculada aos impactos da pandemia de Covid-19 na economia (recesso e desemprego), com impacto perverso aos indiv\u00edduos e, em particular, aos benefici\u00e1rios do INSS\u201d, diz a nota.<\/p>\n<p>A medida foi proposta considerando estat\u00edsticas do Banco Central de julho de 2020, que mostravam que a taxa m\u00e9dia de juros do cr\u00e9dito consignado para benefici\u00e1rios do INSS foi de 1,6% ao m\u00eas, e para o cr\u00e9dito pessoal sem consigna\u00e7\u00e3o, de 5,1% ao m\u00eas. Al\u00e9m disse, segundo a Presid\u00eancia, ao longo da pandemia, a concess\u00e3o de cr\u00e9dito consignado aos benefici\u00e1rios do INSS apresentou crescimento de 27,6% em julho de 2020 (R$ 8,5 bilh\u00f5es), em rela\u00e7\u00e3o a janeiro do mesmo ano.<\/p>\n<p>\u201cOutrossim, levou-se tamb\u00e9m em considera\u00e7\u00e3o que as institui\u00e7\u00f5es financeiras n\u00e3o s\u00e3o obrigadas a acolher todas as solicita\u00e7\u00f5es propostas de concess\u00e3o de cr\u00e9dito, pois a concess\u00e3o de novas linhas de cr\u00e9dito depende da avalia\u00e7\u00e3o de risco de cr\u00e9dito do cliente pela institui\u00e7\u00e3o financeira\u201d, explicou.<\/p>\n<p><strong>Mudan\u00e7as no INSS<\/strong><br \/>\nO texto ainda modificou a lei que trata dos planos de benef\u00edcios da Previd\u00eancia Social, para que as consigna\u00e7\u00f5es de mensalidades de associa\u00e7\u00f5es e de entidades de aposentados legalmente reconhecidas devam ser reavaliadas a cada tr\u00eas anos a partir de 31 de dezembro de 2022, al\u00e9m de possibilitar a prorroga\u00e7\u00e3o desse prazo por mais um ano, por meio de ato do presidente do INSS.<\/p>\n<p>\u201cIsso evitou que o INSS, no meio da pandemia, fosse obrigado a cortar os descontos devidos para associa\u00e7\u00f5es\u201d, explicou a Secretaria-Geral.<\/p>\n<p>Outra modifica\u00e7\u00e3o feita pela lei \u00e9 autorizar o INSS a conceder aux\u00edlio-doen\u00e7a mediante apresenta\u00e7\u00e3o de atestado m\u00e9dico e de documentos complementares &#8211; a serem elencados em ato posterior e conjunto da Secretaria Especial de Previd\u00eancia e Trabalho do Minist\u00e9rio da Economia e do INSS. Antes da mudan\u00e7a, era necess\u00e1rio passar por per\u00edcia para ter o benef\u00edcio.<\/p>\n<p>Essa dispensa tamb\u00e9m tem car\u00e1ter excepcional, at\u00e9 31 de dezembro de 2021, e a dura\u00e7\u00e3o do benef\u00edcio por incapacidade tempor\u00e1ria dele resultante n\u00e3o ter\u00e1 dura\u00e7\u00e3o superior a 90 dias.<\/p>\n<p><span style=\"font-size: 11px;\">Por\u00a0Andreia Verd\u00e9lio\/Rep\u00f3rter da Ag\u00eancia Brasil<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valor deve ser usado para saque e despesas com cart\u00e3o de cr\u00e9dito O Presidente Jair Bolsonaro sancionou a lei que amplia de 35% para 40% margem de empr\u00e9stimo consignado para aposentados e pensionistas do Instituto Nacional do Seguro Social (INSS). O texto foi publicado ontem (31) no Di\u00e1rio Oficial da Uni\u00e3o . De acordo com &#8230;<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,249,16],"tags":[6091,5947,6293,6294,6292,6092,6291],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/31869"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=31869"}],"version-history":[{"count":2,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/31869\/revisions"}],"predecessor-version":[{"id":31871,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/31869\/revisions\/31871"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=31869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=31869"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=31869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}