{"id":29416,"date":"2020-06-19T14:05:56","date_gmt":"2020-06-19T14:05:56","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=29416"},"modified":"2020-06-19T14:06:30","modified_gmt":"2020-06-19T14:06:30","slug":"palavra-do-presidente-3","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/palavra-do-presidente-3\/","title":{"rendered":"Palavra do Presidente 19\/6"},"content":{"rendered":"<p>A <strong>cr\u00edtica<\/strong> da semana vai para os pol\u00edticos que j\u00e1 come\u00e7aram a definir e montar equipes de trabalho, sem mesmo abrir a \u00faltima urna das Elei\u00e7\u00f5es 2020.<\/p>\n<p><strong>NOTA<\/strong><br \/>\nJ\u00e1 est\u00e1 definido quem ser\u00e1 o Presidente da C\u00e2mara Municipal para o bi\u00eanio 2021\/2022, j\u00e1 definiram o Presidente da C\u00e2mara para o bi\u00eanio 2023\/2024, e j\u00e1 definiram o Chefe de Imprensa 2021 a 2024. Caros (caros porque s\u00e3o muito caros para o munic\u00edpio pelo que fazem, n\u00e3o generalizando \u00e9 claro) pol\u00edticos, n\u00e3o seria mais sensato se elegerem primeiro? N\u00e3o se esque\u00e7am de experi\u00eancias amargas anteriormente, e inclusive acredito que um desses candidatos a vereador que dever\u00e1 assumir a presid\u00eancia da C\u00e2mara em 2023 \/2024, nem se eleger\u00e1 quando a \u2018col\u00f4nia\u2019 souber quem ele \u00e9 na verdade, aguarde mat\u00e9ria investigativa sobre esse vereador nas pr\u00f3ximas edi\u00e7\u00f5es no Jornal Exemplo\u00ae. Outro assunto que cogita na cidade, que j\u00e1 definiram o Chefe de Imprensa da C\u00e2mara Municipal. N\u00e3o seria mais sensato aguardar as Elei\u00e7\u00f5es acontecerem para depois definir quem ser\u00e1 o Chefe da Imprensa? N\u00e3o seria mais sensato motivar os \u2018pratas\u2019 da casa, ao inv\u00e9s de colocar um cidad\u00e3o como Chefe de Imprensa da C\u00e2mara Municipal, que vem de outro ve\u00edculo de comunica\u00e7\u00e3o pequeno, sem experi\u00eancia alguma em outras regi\u00f5es somente em Indaiatuba? Bom, vamos analisar e aguardar os pr\u00f3ximos cap\u00edtulos da novela \u2018A Sucess\u00e3o\u2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A cr\u00edtica da semana vai para os pol\u00edticos que j\u00e1 come\u00e7aram a definir e montar equipes de trabalho, sem mesmo abrir a \u00faltima urna das Elei\u00e7\u00f5es 2020. NOTA J\u00e1 est\u00e1 definido quem ser\u00e1 o Presidente da C\u00e2mara Municipal para o bi\u00eanio 2021\/2022, j\u00e1 definiram o Presidente da C\u00e2mara para o bi\u00eanio 2023\/2024, e j\u00e1 definiram &#8230;<\/p>\n","protected":false},"author":30,"featured_media":29417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[106],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/29416"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=29416"}],"version-history":[{"count":2,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/29416\/revisions"}],"predecessor-version":[{"id":29419,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/29416\/revisions\/29419"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/29417"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=29416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=29416"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=29416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}