{"id":2926,"date":"2015-07-30T17:06:27","date_gmt":"2015-07-30T17:06:27","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=2926"},"modified":"2015-07-30T17:06:27","modified_gmt":"2015-07-30T17:06:27","slug":"agosto-das-artes-tera-evento-especial-no-parque-ecologico","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/agosto-das-artes-tera-evento-especial-no-parque-ecologico\/","title":{"rendered":"Agosto das Artes ter\u00e1 evento especial no Parque Ecol\u00f3gico"},"content":{"rendered":"<p>O Festival Agosto das Artes, promovido anualmente pela Secretaria Municipal de Cultura para fomentar o interesse da popula\u00e7\u00e3o pelas artes pl\u00e1sticas em todas as suas manifesta\u00e7\u00f5es, traz este ano uma s\u00e9rie de novidades, a come\u00e7ar pela defini\u00e7\u00e3o da programa\u00e7\u00e3o. Nesta edi\u00e7\u00e3o, a Secretaria contou com a ampla participa\u00e7\u00e3o dos artistas da cidade, que desenvolveram e propuseram em grupo projetos que gostariam de viabilizar no festival. Foi eleito ainda um tema central, Caminhos para a Paz, em alus\u00e3o aos 70 anos do final da Segunda Guerra Mundial completados em 2015, que permear\u00e1 as principais iniciativas. Entre os destaques, no dia 16 de agosto, a partir das 9h, saindo da Prefeitura Municipal, haver\u00e1 a Caminhada pela Paz at\u00e9 o Parque Tem\u00e1tico, onde ser\u00e3o instaladas bandeiras pintadas pelos alunos das oficinas da Secretaria de Cultura e da rede municipal de ensino. J\u00e1 a partir do pr\u00f3ximo dia 5, \u00e0s 19h, ser\u00e1 poss\u00edvel visitar quatro diferentes exposi\u00e7\u00f5es no Centro de Conven\u00e7\u00f5es Aydil Bonachella, entre elas o 1\u00ba Sal\u00e3o de Artes Visuais, com trabalhos de artistas indaiatubanos nas \u00e1reas de pintura, escultura, gravura, instala\u00e7\u00e3o, fotografia, desenho, v\u00eddeo-arte e experimental. Todas as atividades s\u00e3o gratuitas e englobam tamb\u00e9m oficinas e semin\u00e1rio. Confira abaixo a agenda completa e prestigie com a fam\u00edlia e os amigos. Informa\u00e7\u00f5es (19) 3894-1867.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Festival Agosto das Artes, promovido anualmente pela Secretaria Municipal de Cultura para fomentar o interesse da popula\u00e7\u00e3o pelas artes pl\u00e1sticas em todas as suas manifesta\u00e7\u00f5es, traz este ano uma s\u00e9rie de novidades, a come\u00e7ar pela defini\u00e7\u00e3o da programa\u00e7\u00e3o. Nesta edi\u00e7\u00e3o, a Secretaria contou com a ampla participa\u00e7\u00e3o dos artistas da cidade, que desenvolveram e &#8230;<\/p>\n","protected":false},"author":19,"featured_media":2927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,262],"tags":[],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/2926"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=2926"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/2926\/revisions"}],"predecessor-version":[{"id":2928,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/2926\/revisions\/2928"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/2927"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=2926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=2926"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=2926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}