{"id":1612,"date":"2015-05-22T13:46:43","date_gmt":"2015-05-22T13:46:43","guid":{"rendered":"http:\/\/jornalexemplo1.hospedagemdesites.ws\/jornal\/?p=1612"},"modified":"2015-05-22T13:46:43","modified_gmt":"2015-05-22T13:46:43","slug":"passeio-cicloturistico-tera-um-total-de-13km-em-asfalto","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/passeio-cicloturistico-tera-um-total-de-13km-em-asfalto\/","title":{"rendered":"Passeio ciclotur\u00edstico ter\u00e1 um total de 13km em asfalto"},"content":{"rendered":"<p class=\"western\">No domingo, dia 24, a Prefeitura de Indaiatuba, por meio do Departamento de Turismo, vinculado \u00e0 Secretaria de Desenvolvimento, promove mais uma edi\u00e7\u00e3o do j\u00e1 tradicional passeio ciclotur\u00edstico \u201cIndaiatuba by Bike\u201d, \u00e0s 8h30. Nesta edi\u00e7\u00e3o o passeio ter\u00e1 como destino um shopping da cidade que em homenagem ao M\u00eas das M\u00e3es dar\u00e1 brindes aos 100 primeiros participantes do passeio que retirarem senha no dia do evento. A participa\u00e7\u00e3o \u00e9 gratuita e ter\u00e1 um total de 13km no percurso, todo em asfalto, seguindo do Pa\u00e7o Municipal pelo Parque Ecol\u00f3gico e avenidas da cidade at\u00e9 uma \u00e1rea de mata e nascentes onde haver\u00e1 parada para lanche. Desse local, ser\u00e1 feito o retorno at\u00e9 o encerramento do passeio no shopping onde os participantes poder\u00e3o desfrutar do espa\u00e7o. A dura\u00e7\u00e3o ser\u00e1 de aproximadamente tr\u00eas horas e meia, ter\u00e1 apoio do Departamento de Tr\u00e2nsito; Ambul\u00e2ncia; Servi\u00e7o Aut\u00f4nomo de \u00c1gua e Esgoto (Saae) e tamb\u00e9m parceria da Faculdade Max Planck e Nutriplus.<\/p>\n<p class=\"western\">Para participar basta comparecer com a bicicleta ao estacionamento do Pa\u00e7o Municipal. O mesmo \u00e9 indicado para maiores de 10 anos, sendo que os menores devem ser acompanhados dos respons\u00e1veis. O percurso \u00e9 de baixa dificuldade e durante o trajeto haver\u00e1 paradas para hidrata\u00e7\u00e3o. Em caso de chuva o passeio ser\u00e1 cancelado.<\/p>\n<p class=\"western\"><strong><em>Conhe\u00e7a o Indaiatuba By Bike<\/em><\/strong><\/p>\n<p class=\"western\">Projeto criado h\u00e1 mais de 5 anos pelo Departamento de Turismo da Prefeitura Municipal, o Indaiatuba by Bike ganha mais adeptos a cada edi\u00e7\u00e3o e \u00e9 uma \u00f3tima op\u00e7\u00e3o de lazer para toda a fam\u00edlia com uma programa\u00e7\u00e3o que alterna trajetos urbanos e rurais, com diferentes n\u00edveis de dificuldade, sempre contemplando pontos de interesse tur\u00edstico, cultural e ambiental al\u00e9m de proporcionar atividade f\u00edsica.<\/p>\n<p class=\"western\">Aqueles que tiverem interesse podem se inscrever no link: www.indaiatuba.sp.gov.br\/desenvolvimento\/turismo\/inscricao-by-bike\/ para receber informa\u00e7\u00f5es sobre as pr\u00f3ximas edi\u00e7\u00f5es do passeio que ocorre mensalmente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No domingo, dia 24, a Prefeitura de Indaiatuba, por meio do Departamento de Turismo, vinculado \u00e0 Secretaria de Desenvolvimento, promove mais uma edi\u00e7\u00e3o do j\u00e1 tradicional passeio ciclotur\u00edstico \u201cIndaiatuba by Bike\u201d, \u00e0s 8h30. Nesta edi\u00e7\u00e3o o passeio ter\u00e1 como destino um shopping da cidade que em homenagem ao M\u00eas das M\u00e3es dar\u00e1 brindes aos 100 &#8230;<\/p>\n","protected":false},"author":16,"featured_media":1613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[264,16],"tags":[321],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/1612"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=1612"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/1612\/revisions"}],"predecessor-version":[{"id":1614,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/1612\/revisions\/1614"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media\/1613"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=1612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=1612"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=1612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}