{"id":15255,"date":"2017-07-21T12:37:04","date_gmt":"2017-07-21T12:37:04","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=15255"},"modified":"2017-07-21T12:37:04","modified_gmt":"2017-07-21T12:37:04","slug":"lula-sera-interrogado-em-mais-um-processo","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/lula-sera-interrogado-em-mais-um-processo\/","title":{"rendered":"Lula ser\u00e1 interrogado em mais um processo"},"content":{"rendered":"<p>Ag\u00eancia Brasil \/\u00a0Daniel Isaia<\/p>\n<p>O juiz S\u00e9rgio Moro, da 13\u00aa Vara Federal de Curitiba, marcou para 13 de setembro o interrogat\u00f3rio do ex-presidente Luiz In\u00e1cio Lula da Silva no segundo processo a que ele responde derivado da Opera\u00e7\u00e3o Lava Jato.<br \/>\nNa a\u00e7\u00e3o penal, o Minist\u00e9rio P\u00fablico Federal (MPF) acusa o ex-presidente de ter recebido da Odebrecht um apartamento em S\u00e3o Bernardo do Campo (SP) e um terreno em S\u00e3o Paulo para constru\u00e7\u00e3o da sede do Instituto Lula. Segundo a den\u00fancia, em troca, a empreiteira foi beneficiada em contratos com a Petrobras.<br \/>\nO despacho publicado ontem (20) cita o interrogat\u00f3rio do ex-presidente realizado em maio, no processo em que ele foi condenado em primeira inst\u00e2ncia. De acordo com Moro, aquela sess\u00e3o \u201cacabou envolvendo gastos necess\u00e1rios, mas indesej\u00e1veis, de recursos p\u00fablicos com medidas de seguran\u00e7a\u201d.<br \/>\nSob essa argumenta\u00e7\u00e3o, o juiz pediu \u00e0 defesa de Lula que se manifestasse sobre a possibilidade de realizar o interrogat\u00f3rio por meio de videoconfer\u00eancia.<br \/>\nNo dia 4 de setembro, ser\u00e3o interrogados os empres\u00e1rios Marcelo Odebrecht, Dermeval de Souza Gusm\u00e3o Filho e o executivo Paulo Ricardo Baqueiro de Melo. No dia 6, ser\u00e3o ouvidos o ex-ministro Ant\u00f4nio Palocci, o advogado Roberto Teixeira e Glaucos da Costa Marques, primo do pecuarista Jos\u00e9 Carlos Bumlai. Branislav Kontic, ex-assessor de Palocci, ser\u00e1 interrogado no mesmo dia que Lula.<\/p>\n<p>Bloqueio<br \/>\nO Banco Central bloqueou na quarta-feira (19) R$ 606,7 mil das contas do ex-presidente Luiz In\u00e1cio Lula da Silva. A ordem foi expedida pelo juiz S\u00e9rgio Moro, da 13\u00aa Vara Federal de Curitiba, no dia 14 de julho, mas estava sob sigilo at\u00e9 que o bloqueio fosse realizado.<br \/>\nA decis\u00e3o foi tomada para fins de repara\u00e7\u00e3o de danos \u00e0 Petrobras no processo em que o petista foi condenado a 9 anos e meio em primeira inst\u00e2ncia, no \u00e2mbito da Opera\u00e7\u00e3o Lava Jato. O juiz tamb\u00e9m determinou o confisco de im\u00f3veis e ve\u00edculos do ex-presidente.<br \/>\n\u201cEm s\u00edntese, reconhecido que o contrato celebrado entre o Cons\u00f3rcio Conest\/Rnest gerou cerca de R$ 16 milh\u00f5es em vantagem indevida a agentes do Partido dos Trabalhadores (PT), deles sendo destinados especificamente cerca de R$ 2.252.472 ao ex-presidente Luiz In\u00e1cio Lula da Silva na forma da atribui\u00e7\u00e3o a ele de apartamento no Guaruj\u00e1, sem o pagamento do pre\u00e7o correspondente, e da realiza\u00e7\u00e3o de reformas no apartamento \u00e0s expensas da OAS\u201d, escreveu Moro na decis\u00e3o.<\/p>\n<div class=\"mom-members\" style=\"background-color:#ffe680;border-color:#cca300;color:#665200\">Conte\u00fado somente para assinantes. Por favor fa\u00e7a o login<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ag\u00eancia Brasil \/\u00a0Daniel Isaia O juiz S\u00e9rgio Moro, da 13\u00aa Vara Federal de Curitiba, marcou para 13 de setembro o interrogat\u00f3rio do ex-presidente Luiz In\u00e1cio Lula da Silva no segundo processo a que ele responde derivado da Opera\u00e7\u00e3o Lava Jato. Na a\u00e7\u00e3o penal, o Minist\u00e9rio P\u00fablico Federal (MPF) acusa o ex-presidente de ter recebido da &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[258],"tags":[2649],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/15255"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=15255"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/15255\/revisions"}],"predecessor-version":[{"id":15256,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/15255\/revisions\/15256"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=15255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=15255"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=15255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}