{"id":13595,"date":"2017-04-14T06:02:55","date_gmt":"2017-04-14T06:02:55","guid":{"rendered":"http:\/\/www.jornalexemplo.com.br\/jornal\/?p=13595"},"modified":"2017-04-12T20:04:16","modified_gmt":"2017-04-12T20:04:16","slug":"resultado-da-triagem-estara-disponivel","status":"publish","type":"post","link":"http:\/\/www.jornalexemplo.com.br\/jornal\/resultado-da-triagem-estara-disponivel\/","title":{"rendered":"Resultado  da triagem  estar\u00e1  dispon\u00edvel"},"content":{"rendered":"<p>DA REDA\u00c7\u00c3O<\/p>\n<p>Est\u00e3o encerradas as inscri\u00e7\u00f5es para o 16\u00ba Pr\u00eamio Nabor Pires Camargo \u2013 Instrumentista. Foram recebidas inscri\u00e7\u00f5es, de diversos estados: Minas Gerais, S\u00e3o Paulo, Paran\u00e1, Distrito Federal, Mato Grosso do Sul. Rio Grande do Sul, Bahia e Rio de Janeiro.<br \/>\nO resultado da triagem estar\u00e1 dispon\u00edvel a partir de segunda-feira, dia 17, \u00e0s 14hs, no site www.promemoria.indaiatuba.sp.gov.br. A audi\u00e7\u00e3o final que definir\u00e1 os vencedores ocorrer\u00e1 no sexta-feira, dia 28, \u00e0s 19h30, no Centro Integrado de Apoio \u00e0 Educa\u00e7\u00e3o de Indaiatuba (Ciaei) e ter\u00e1 entrada gratuita.<br \/>\nO evento ser\u00e1 apresentado pelo produtor e apresentador do Programa Chorinho Brasil na Rede Boa Nova de R\u00e1dio, Jo\u00e3o Tom\u00e1s do Amaral. O encerramento contar\u00e1 com a participa\u00e7\u00e3o do vencedor da \u00faltima edi\u00e7\u00e3o do pr\u00eamio, o clarinetista Andr\u00e9 Fajersztajn de Almeida acompanhado por Jo\u00e3o Nicolau de Almeida, Get\u00falio Franco Ribeiro e Ivan Banho formando o Conjunto Paulistano.<\/p>\n<div class=\"mom-members\" style=\"background-color:#ffe680;border-color:#cca300;color:#665200\">Conte\u00fado somente para assinantes. Por favor fa\u00e7a o login<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DA REDA\u00c7\u00c3O Est\u00e3o encerradas as inscri\u00e7\u00f5es para o 16\u00ba Pr\u00eamio Nabor Pires Camargo \u2013 Instrumentista. Foram recebidas inscri\u00e7\u00f5es, de diversos estados: Minas Gerais, S\u00e3o Paulo, Paran\u00e1, Distrito Federal, Mato Grosso do Sul. Rio Grande do Sul, Bahia e Rio de Janeiro. O resultado da triagem estar\u00e1 dispon\u00edvel a partir de segunda-feira, dia 17, \u00e0s 14hs, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[261],"tags":[2391],"_links":{"self":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/13595"}],"collection":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/comments?post=13595"}],"version-history":[{"count":1,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/13595\/revisions"}],"predecessor-version":[{"id":13596,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/posts\/13595\/revisions\/13596"}],"wp:attachment":[{"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/media?parent=13595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/categories?post=13595"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jornalexemplo.com.br\/jornal\/wp-json\/wp\/v2\/tags?post=13595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}